{"id":10147,"date":"2022-01-31T10:34:15","date_gmt":"2022-01-31T08:34:15","guid":{"rendered":"https:\/\/www.clinicabaviera.com\/blog\/?p=10147"},"modified":"2025-02-25T16:23:59","modified_gmt":"2025-02-25T15:23:59","slug":"zumo-de-apio-propiedades-cuidar-salud-visual","status":"publish","type":"post","link":"https:\/\/www.clinicabaviera.com\/blog\/zumo-de-apio-propiedades-cuidar-salud-visual\/","title":{"rendered":"\u00bfPor qu\u00e9 el zumo de apio ayuda a cuidar la vista?"},"content":{"rendered":"\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-left kksr-valign-top\"\n    data-payload='{&quot;align&quot;:&quot;left&quot;,&quot;id&quot;:&quot;10147&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;top&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;112&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;4.9&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;4&quot;,&quot;greet&quot;:&quot;Rate this post&quot;,&quot;legend&quot;:&quot;4.9\\\/5 - (112 votos)&quot;,&quot;size&quot;:&quot;15&quot;,&quot;title&quot;:&quot;\u00bfPor qu\u00e9 el zumo de apio ayuda a cuidar la vista?&quot;,&quot;width&quot;:&quot;91.1&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 91.1px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 12px;\">\n            4.9\/5 - (112 votos)    <\/div>\n    <\/div>\n<p><span style=\"font-weight: 400;\">El <\/span><b>zumo de apio<\/b><span style=\"font-weight: 400;\"> (y, por supuesto, el apio en su forma natural) es un ingrediente al que se le atribuyen muchas propiedades, entre las que se encuentran\u00a0 el cuidado y la conservaci\u00f3n de nuestra salud visual. En este art\u00edculo te explicamos cu\u00e1les son las principales propiedades que hacen que incluir esta verdura en tu dieta habitual sea una buena forma de cuidar de la salud de tus ojos.\u00a0<\/span><\/p>\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 ez-toc-wrap-center counter-hierarchy ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">\u00cdndice<\/p>\n<span class=\"ez-toc-title-toggle\"><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.clinicabaviera.com\/blog\/zumo-de-apio-propiedades-cuidar-salud-visual\/#%C2%BFEs_el_zumo_de_apio_malo_para_la_vista\" >\u00bfEs el zumo de apio malo para la vista?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.clinicabaviera.com\/blog\/zumo-de-apio-propiedades-cuidar-salud-visual\/#El_apio_una_verdura_usada_desde_la_antiguedad\" >El apio: una verdura usada desde la antig\u00fcedad<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.clinicabaviera.com\/blog\/zumo-de-apio-propiedades-cuidar-salud-visual\/#%C2%BFDe_que_forma_ayuda_el_apio_a_nuestros_ojos\" >\u00bfDe qu\u00e9 forma ayuda el apio a nuestros ojos?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.clinicabaviera.com\/blog\/zumo-de-apio-propiedades-cuidar-salud-visual\/#%C2%BFCuales_son_las_propiedades_del_apio\" >\u00bfCu\u00e1les son las propiedades del apio?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/www.clinicabaviera.com\/blog\/zumo-de-apio-propiedades-cuidar-salud-visual\/#%C2%BFComo_preparar_zumo_de_apio\" >\u00bfC\u00f3mo preparar zumo de apio?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/www.clinicabaviera.com\/blog\/zumo-de-apio-propiedades-cuidar-salud-visual\/#Mas_alla_del_zumo_de_apio_crudites_de_apio\" >M\u00e1s all\u00e1 del zumo de apio: crudit\u00e9s de apio<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"%C2%BFEs_el_zumo_de_apio_malo_para_la_vista\"><\/span><span style=\"font-weight: 400;\">\u00bfEs el zumo de apio malo para la vista?<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Existe una creencia bastante extendida entre la poblaci\u00f3n que afirma que el zumo de apio no ser\u00eda bueno para la vista, sino todo lo contrario. Esta creencia es sencillamente falsa. El apio es una planta de la familia de las umbel\u00edferas (la misma que la del perejil, el hinojo y otros alimentos similares) que aporta beneficios para mantener una buena visi\u00f3n y una buena salud visual.<\/span><\/p>\n<p><a href=\"https:\/\/cloud.info.clinicabaviera.com\/recetas\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-35888 size-full\" src=\"https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/2024\/02\/Recetas_vistas_horizontal.jpg\" alt=\"\" width=\"751\" height=\"367\" srcset=\"https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/2024\/02\/Recetas_vistas_horizontal.jpg 751w, https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/2024\/02\/Recetas_vistas_horizontal-300x147.jpg 300w, https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/2024\/02\/Recetas_vistas_horizontal-200x98.jpg 200w\" sizes=\"auto, (max-width: 751px) 100vw, 751px\" \/><\/a><\/p>\n<h2><span class=\"ez-toc-section\" id=\"El_apio_una_verdura_usada_desde_la_antiguedad\"><\/span><span style=\"font-weight: 400;\">El apio: una verdura usada desde la antig\u00fcedad<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Se cree que estos beneficios del apio ya eran conocidos desde los tiempos de la antigua Grecia. De hecho, algunos historiadores e investigadores creen que esta planta es la misma que menciona el poeta Homero en <\/span><i><span style=\"font-weight: 400;\">La Odisea<\/span><\/i><span style=\"font-weight: 400;\">, el poema \u00e9pico por excelencia donde se le llama \u201cselenion\u201d, t\u00e9rmino que luego deriv\u00f3 en el franc\u00e9s \u201cceleri\u201d.<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-27750 size-large\" src=\"https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/2019\/09\/apio-840x560.jpg\" alt=\"Apio y zumo de apio\" width=\"840\" height=\"560\" srcset=\"https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/2019\/09\/apio-840x560.jpg 840w, https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/2019\/09\/apio-300x200.jpg 300w, https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/2019\/09\/apio-200x133.jpg 200w, https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/2019\/09\/apio-768x512.jpg 768w, https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/2019\/09\/apio.jpg 1250w\" sizes=\"auto, (max-width: 840px) 100vw, 840px\" \/><\/p>\n<h2><span class=\"ez-toc-section\" id=\"%C2%BFDe_que_forma_ayuda_el_apio_a_nuestros_ojos\"><\/span><span style=\"font-weight: 400;\">\u00bfDe qu\u00e9 forma ayuda el apio a nuestros ojos?<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"font-weight: 400;\">El apio es una hortaliza a la que se le atribuyen m\u00faltiples propiedades para mantener una buena salud visual, tal y como pasa con otros alimentos como la zanahoria, la frambuesa, la pi\u00f1a,\u00a0 <\/span><a href=\"https:\/\/www.clinicabaviera.com\/blog\/batido-melon-platano-proteger-vista\/\"><span style=\"font-weight: 400;\">el mel\u00f3n y el pl\u00e1tano<\/span><\/a><span style=\"font-weight: 400;\">, entre otros.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En este sentido, hay que tener en cuenta que no es que tomar apio o zumo de apio vaya a ayudar solo a nuestros ojos, sino que algunos de sus elementos nutricionales influyen positivamente en toda nuestra salud y, en concreto, en la salud visual. Esto se debe a que los ojos son \u00f3rganos delicados y que necesitan ser cuidados a lo largo de toda nuestra vida y el apio es un alimento que contiene muchos de los micronutrientes esenciales para una buena salud visual y general.\u00a0<\/span><\/p>\n<h2><span class=\"ez-toc-section\" id=\"%C2%BFCuales_son_las_propiedades_del_apio\"><\/span><span style=\"font-weight: 400;\">\u00bfCu\u00e1les son las propiedades del apio?<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Algunas de las propiedades del apio que nos van a ayudar a cuidar de nuestra salud son las siguientes:\u00a0<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Reduce el colesterol en la sangre<\/span><span style=\"font-weight: 400;\">. Al hacerlo, disminuye las posibilidades de que suframos obesidad y que, por tanto, se favorezca la aparici\u00f3n de anomal\u00edas visuales derivadas del sobrepeso y el colesterol alto.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Disminuye los niveles de glucemia en la sangre<\/span><span style=\"font-weight: 400;\">. Es decir, la sangre que irriga la zona ocular es de mejor calidad cuando consumimos apio en cualquiera de sus variantes, incluido el zumo de apio.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Depura el organismo<\/span><span style=\"font-weight: 400;\">. Gracias a su alto contenido en agua, vitaminas y minerales, se trata de un complemento perfecto que ayuda a nuestro h\u00edgado y a nuestros ri\u00f1ones a trabajar correctamente y eliminar toxinas del cuerpo.\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Forma parte de una dieta saludable que previene la diabetes<\/span><span style=\"font-weight: 400;\">. Si lo consumimos habitualmente, las probabilidades de que suframos enfermedades como la diabetes son menores, algo que, al mismo tiempo, nos ayuda a prevenir las anomal\u00edas visuales causadas por esta disfunci\u00f3n, como por ejemplo algunos tipos de <\/span><a href=\"https:\/\/www.clinicabaviera.com\/glaucoma\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">glaucoma <\/span><\/a><span style=\"font-weight: 400;\">o la retinopat\u00eda diab\u00e9tica<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Es una fuente importante de vitaminas y minerales<\/span><span style=\"font-weight: 400;\">. Al igual que la mayor\u00eda de las verduras, el apio constituye una buena fuente de minerales y vitaminas, fundamentales para el correcto funcionamiento de nuestro organismo, por lo que su consumo habitual ayuda a proteger nuestra salud, incluida la de nuestros ojos. El apio es una importante fuente de vitamina C, un potente antioxidante necesario en multitud de procesos de nuestro cuerpo, incluida la regeneraci\u00f3n celular y de los tejidos. Sin embargo, para aprovechar al m\u00e1ximo esta vitamina, es necesario consumir el apio crudo, ya que, cuando esta vitamina se calienta, se degrada.\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Mejora las digestiones y ayuda a la salud de nuestro intestino<\/span><span style=\"font-weight: 400;\">. Esto se debe a que el apio es una importante fuente de fibra vegetal, la cual ayuda a nuestro tubo digestivo a realizar mejor las funciones de evacuaci\u00f3n de las heces. Esto permite tener un colon saludable y una correcta microbiota, lo que repercute positivamente en el conjunto de nuestra salud.\u00a0<\/span><\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"%C2%BFComo_preparar_zumo_de_apio\"><\/span><span style=\"font-weight: 400;\">\u00bfC\u00f3mo preparar zumo de apio?<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Una forma sencilla, nutritiva y r\u00e1pida de consumir el apio es preparando un rico batido o un zumo de esta verdura que podamos tomar en cualquier momento.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Para potenciar su efecto positivo en la salud visual, puedes combinarlo con ingredientes como la zanahoria u otras verduras como el pepino, la espinaca, el perejil y cualquier tipo de col. Al hacerlo, no solo tendr\u00e1s un zumo m\u00e1s sabroso, sino tambi\u00e9n mucho m\u00e1s nutritivo y rico en <\/span><a href=\"https:\/\/www.clinicabaviera.com\/blog\/alimentos-con-magnesio-y-zinc-y-sus-beneficios-para-los-ojos\/\"><span style=\"font-weight: 400;\">micronutrientes<\/span><\/a><span style=\"font-weight: 400;\">, fundamentales para disfrutar de una correcta salud ocular y general y prevenir enfermedades.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La textura del batido o zumo de apio depender\u00e1, tanto de los ingredientes como del procedimiento de licuado. Si lo haces en una licuadora o batidora, suele recomendarse pasarlo luego por un colador para retirar el exceso de fibras. Sin embargo, es importante recordar que toda esa fibra es muy saludable para nuestro organismo, por lo que se recomienda usar un colador que no la elimine por completo. De esta forma, podremos aprovechar al m\u00e1ximo todas sus propiedades y beneficios para la salud.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Adem\u00e1s, si se combina con ciertas especias como la pimienta o un ligero toque picante, se conseguir\u00e1 potenciar el sabor del zumo de apio. De esta forma, adem\u00e1s de ser una bomba de vitaminas y minerales baja en calor\u00edas, tambi\u00e9n se convertir\u00e1 en un aperitivo perfecto para cualquier ocasi\u00f3n, tanto para recuperar l\u00edquidos despu\u00e9s del gimnasio como para tomar algo fresco en una reuni\u00f3n con amigos.\u00a0<\/span><\/p>\n<p><span class=\"embed-youtube\" style=\"text-align:center; display: block;\"><iframe loading=\"lazy\" class=\"youtube-player\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/saInQ_b514E?version=3&#038;rel=1&#038;showsearch=0&#038;showinfo=1&#038;iv_load_policy=1&#038;fs=1&#038;hl=es-ES&#038;autohide=2&#038;wmode=transparent\" allowfullscreen=\"true\" style=\"border:0;\" sandbox=\"allow-scripts allow-same-origin allow-popups allow-presentation allow-popups-to-escape-sandbox\"><\/iframe><\/span><\/p>\n<h2><span class=\"ez-toc-section\" id=\"Mas_alla_del_zumo_de_apio_crudites_de_apio\"><\/span><span style=\"font-weight: 400;\">M\u00e1s all\u00e1 del zumo de apio: crudit\u00e9s de apio<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Por otro lado, aunque el zumo de apio es una de las formas m\u00e1s habituales y c\u00f3modas de consumir esta hortaliza, existen otras maneras sencillas y muy sabrosas de hacerlo. Una de ellas son los crudit\u00e9s de apio, que se preparan de forma sencilla y que gustan a todo el mundo.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Para preparar crudit\u00e9s de apio basta con cortar el apio en tiras finas que puedan ser cogidas directamente con los dedos. A continuaci\u00f3n, se utilizan estas tiras de apio para mojarlas en diferentes salsas, lo que le aportar\u00e1 m\u00e1s sabor al bocado. Existen muchas opciones para ello, aunque las m\u00e1s comunes suelen ser el humus y la crema agria. En ambos casos, se trata de salsas que aportan un contenido interesante en prote\u00ednas, pero bajas en calor\u00edas. Lo que, combinado con las vitaminas y minerales de los crudit\u00e9s de apio, lo convierte en el aperitivo saludable perfecto.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por otro lado, a la hora de preparar los crudit\u00e9s de apio, lo m\u00e1s recomendable es escoger las partes m\u00e1s tiernas del apio. Esto se debe a que, como se ha mencionado, el apio tiene mucha fibra, lo que puede hacer que las partes m\u00e1s duras sean algo m\u00e1s dif\u00edciles de masticar. Sin embargo, seleccionado las partes tiernas para los crudit\u00e9s, se podr\u00e1n reservar las duras para preparar zumo de apio, lo que servir\u00e1 para aprovechar al 100% todas las partes de la planta.<\/span><\/p>\n<hr \/>\n<pre class=\"ti-widget\" style=\"display: none\"><template id=\"trustindex-google-widget-html\"><div class=\" ti-widget  ti-goog ti-review-text-mode-readmore ti-text-align-left\" data-no-translation=\"true\" data-plugin-version=\"13.2.9\" data-layout-id=\"5\" data-layout-category=\"slider\" data-set-id=\"light-minimal\" data-pid=\"\" data-language=\"es\" data-close-locale=\"Cerca\" data-review-target-width=\"275\" data-css-version=\"2\" data-reply-by-locale=\"Respuesta del propietario\" data-only-rating-locale=\"Esta usuario solo dej\u00f3 una calificaci\u00f3n.\" data-pager-autoplay-timeout=\"6\"> <div class=\"ti-widget-container ti-col-4\"> <div class=\"ti-footer ti-footer-grid source-Google\"> <div class=\"ti-fade-container\"> <div class=\"ti-rating-text\"> <strong class=\"ti-rating ti-rating-large\"> EXCELENTE <\/strong> <\/div> <span class=\"ti-stars star-lg\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><\/span> <div class=\"ti-rating-text\"> <span class=\"nowrap\">A base de <strong>570 rese\u00f1as<\/strong><\/span> <\/div> <div class=\"ti-large-logo\"> <div class=\"ti-v-center\"> <trustindex-image class=\"ti-logo-fb\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/logo.svg\" width=\"150\" height=\"25\" loading=\"lazy\" alt=\"Google\"><\/trustindex-image> <\/div> <\/div> <\/div> <\/div> <div class=\"ti-reviews-container\"> <div class=\"ti-controls\"> <div class=\"ti-next\" aria-label=\"Siguiente rese\u00f1a\" role=\"button\" tabindex=\"0\"><\/div> <div class=\"ti-prev\" aria-label=\"Rese\u00f1a anterior\" role=\"button\" tabindex=\"0\"><\/div> <\/div> <div class=\"ti-reviews-container-wrapper\">  <div data-empty=\"0\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-time=\"\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publicado en Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocKWHKmwDoN8jelN8JHWQw2buiU4ji6WyuVq8pcV4kRI=w40-h40-c-rp-mo-br100\" alt=\"Karelys Asencio Torres profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Karelys Asencio Torres <\/div> <div class=\"ti-date\">05\/03\/2024<\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex verifica que la fuente original de la rese\u00f1a sea Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Esta cl\u00ednica sin duda es la mejor !! El trato en recepci\u00f3n y de los m\u00e9dicos es excepcional. Estoy muy contenta con los resultados. Muchas gracias !<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Ocultar\" data-open-text=\"Leer m\u00e1s\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-time=\"\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publicado en Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocJx5lc8VzH_Kx5vNl4iC9Qof6IGYcXj03vtn_CJ67tj=w40-h40-c-rp-mo-br100\" alt=\"Vanesa Delgado Arcos profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Vanesa Delgado Arcos <\/div> <div class=\"ti-date\">01\/03\/2024<\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex verifica que la fuente original de la rese\u00f1a sea Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Much\u00edsima profesionalidad por parte de todo el equipo desde recepci\u00f3n y por supuesto si doctor.Estoy totalmente complacida por el resultado de la operaci\u00f3n y posteriores seguimientos.100%recomendable.<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Ocultar\" data-open-text=\"Leer m\u00e1s\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-time=\"\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publicado en Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjViSSX9rp-UKWvltgBF-J8MwK4Ga5nbJvaYsl3jYkAh2LQ=w40-h40-c-rp-mo-br100\" alt=\"Jorge Carnicero profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Jorge Carnicero <\/div> <div class=\"ti-date\">27\/02\/2024<\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex verifica que la fuente original de la rese\u00f1a sea Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Me oper\u00e9 ya hace un mes con laser de miop\u00eda y no pude tomar mejor decisi\u00f3n, buen asesoramiento desde el principio, un equipo maravilloso que est\u00e1n disponibles para cualquier consulta y unos resultados \u00f3ptimos, sensaci\u00f3n inmejorable poder ver otra vez perfectamente sin necesidad de gafas.<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Ocultar\" data-open-text=\"Leer m\u00e1s\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-time=\"\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publicado en Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocLf5YTDoqTOI9RiEgIqmgY0sL1jjWzGDFlZUKGefO3E=w40-h40-c-rp-mo-br100\" alt=\"Carlos \u00c1ngel P\u00e9rez profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Carlos \u00c1ngel P\u00e9rez <\/div> <div class=\"ti-date\">27\/02\/2024<\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex verifica que la fuente original de la rese\u00f1a sea Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Atenci\u00f3n muy buena de la doctora y de las auxiliares<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Ocultar\" data-open-text=\"Leer m\u00e1s\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-time=\"\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publicado en Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocLJ9j-vNwboPm0yglVXrs4FTPEon3Om3ZTJi7xaqcjl=w40-h40-c-rp-mo-br100\" alt=\"Virginia Jimenez profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Virginia Jimenez <\/div> <div class=\"ti-date\">22\/02\/2024<\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex verifica que la fuente original de la rese\u00f1a sea Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->He recibido un trato espectacular por parte de todos los trabajadores de la cl\u00ednica de M\u00f3stoles.\nLa operaci\u00f3n me la realiz\u00f3 el doctor Rafael, y sali\u00f3 todo muy muy bien me operado de miop\u00eda y astigmatismo, y el mismo d\u00eda por la noche ya pod\u00eda ver y hacer vida normal. Lo recomiendo 100 por 100.\nLlegue con miedo por que la vista es algo muy delicado y a d\u00eda de hoy la mejor decisi\u00f3n que tom\u00e9 fue quitarme las gafas y hacerlo con ellos.\n\nGracias<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Ocultar\" data-open-text=\"Leer m\u00e1s\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-time=\"\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publicado en Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjVdbd3Sm-F_C3qjnSPIEeZ28H3K404OeYdISk2TIzCrhH0=w40-h40-c-rp-mo-ba2-br100\" alt=\"Isidro Hoyas profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Isidro Hoyas <\/div> <div class=\"ti-date\">20\/02\/2024<\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex verifica que la fuente original de la rese\u00f1a sea Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Buenos profesionales y las chicas muy amables y atentas<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Ocultar\" data-open-text=\"Leer m\u00e1s\"><\/span> <\/div> <\/div>  <\/div> <div class=\"ti-controls-line\"> <div class=\"dot\"><\/div> <\/div>   <\/div> <\/div> <\/div> <\/template><\/pre><div data-src=\"https:\/\/cdn.trustindex.io\/loader.js?wp-widget\" data-template-id=\"trustindex-google-widget-html\" data-css-url=\"https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/trustindex-google-widget.css?1774511208\"><\/div>\n<hr \/>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El zumo de apio (y, por supuesto, el apio en su forma natural) es un ingrediente al que se le atribuyen muchas propiedades, entre las que se encuentran\u00a0 el cuidado y la conservaci\u00f3n de nuestra salud visual. En este art\u00edculo te explicamos cu\u00e1les son las principales propiedades que hacen que incluir esta verdura en tu [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":27750,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1145],"tags":[1851],"ppma_author":[2261],"class_list":["post-10147","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estilo-de-vida","tag-zumo-de-apio-propiedades"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfPor qu\u00e9 el zumo de apio ayuda a cuidar la vista?<\/title>\n<meta name=\"description\" content=\"Te contamos las propiedades y beneficios del zumo de apio y por qu\u00e9 debes incluir esta verdura en tu dieta habitual para cuidar de tu salud.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.clinicabaviera.com\/blog\/zumo-de-apio-propiedades-cuidar-salud-visual\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfPor qu\u00e9 el zumo de apio ayuda a cuidar la vista?\" \/>\n<meta property=\"og:description\" content=\"Te contamos las propiedades y beneficios del zumo de apio y por qu\u00e9 debes incluir esta verdura en tu dieta habitual para cuidar de tu salud.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.clinicabaviera.com\/blog\/zumo-de-apio-propiedades-cuidar-salud-visual\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog de Baviera antes Cl\u00ednica Baviera\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CLINICABAVIERA\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-31T08:34:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-25T15:23:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/2019\/09\/apio.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1250\" \/>\n\t<meta property=\"og:image:height\" content=\"833\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dr. Jos\u00e9 Ignacio Valls\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dr. Jos\u00e9 Ignacio Valls\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfPor qu\u00e9 el zumo de apio ayuda a cuidar la vista?","description":"Te contamos las propiedades y beneficios del zumo de apio y por qu\u00e9 debes incluir esta verdura en tu dieta habitual para cuidar de tu salud.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.clinicabaviera.com\/blog\/zumo-de-apio-propiedades-cuidar-salud-visual\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfPor qu\u00e9 el zumo de apio ayuda a cuidar la vista?","og_description":"Te contamos las propiedades y beneficios del zumo de apio y por qu\u00e9 debes incluir esta verdura en tu dieta habitual para cuidar de tu salud.","og_url":"https:\/\/www.clinicabaviera.com\/blog\/zumo-de-apio-propiedades-cuidar-salud-visual\/","og_site_name":"Blog de Baviera antes Cl\u00ednica Baviera","article_publisher":"https:\/\/www.facebook.com\/CLINICABAVIERA","article_published_time":"2022-01-31T08:34:15+00:00","article_modified_time":"2025-02-25T15:23:59+00:00","og_image":[{"width":1250,"height":833,"url":"https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/2019\/09\/apio.jpg","type":"image\/jpeg"}],"author":"Dr. Jos\u00e9 Ignacio Valls","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Dr. Jos\u00e9 Ignacio Valls","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.clinicabaviera.com\/blog\/zumo-de-apio-propiedades-cuidar-salud-visual\/#article","isPartOf":{"@id":"https:\/\/www.clinicabaviera.com\/blog\/zumo-de-apio-propiedades-cuidar-salud-visual\/"},"author":{"name":"Dr. Jose Ignacio Valls","@id":"https:\/\/www.clinicabaviera.com\/blog\/#\/schema\/person\/3a838782fb6ef3b012ece10596a57a87"},"headline":"\u00bfPor qu\u00e9 el zumo de apio ayuda a cuidar la vista?","datePublished":"2022-01-31T08:34:15+00:00","dateModified":"2025-02-25T15:23:59+00:00","mainEntityOfPage":{"@id":"https:\/\/www.clinicabaviera.com\/blog\/zumo-de-apio-propiedades-cuidar-salud-visual\/"},"wordCount":1259,"commentCount":0,"publisher":{"@id":"https:\/\/www.clinicabaviera.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.clinicabaviera.com\/blog\/zumo-de-apio-propiedades-cuidar-salud-visual\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/2019\/09\/apio.jpg","keywords":["zumo de apio propiedades"],"articleSection":["Estilo de vida"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.clinicabaviera.com\/blog\/zumo-de-apio-propiedades-cuidar-salud-visual\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.clinicabaviera.com\/blog\/zumo-de-apio-propiedades-cuidar-salud-visual\/","url":"https:\/\/www.clinicabaviera.com\/blog\/zumo-de-apio-propiedades-cuidar-salud-visual\/","name":"\u00bfPor qu\u00e9 el zumo de apio ayuda a cuidar la vista?","isPartOf":{"@id":"https:\/\/www.clinicabaviera.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.clinicabaviera.com\/blog\/zumo-de-apio-propiedades-cuidar-salud-visual\/#primaryimage"},"image":{"@id":"https:\/\/www.clinicabaviera.com\/blog\/zumo-de-apio-propiedades-cuidar-salud-visual\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/2019\/09\/apio.jpg","datePublished":"2022-01-31T08:34:15+00:00","dateModified":"2025-02-25T15:23:59+00:00","description":"Te contamos las propiedades y beneficios del zumo de apio y por qu\u00e9 debes incluir esta verdura en tu dieta habitual para cuidar de tu salud.","breadcrumb":{"@id":"https:\/\/www.clinicabaviera.com\/blog\/zumo-de-apio-propiedades-cuidar-salud-visual\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.clinicabaviera.com\/blog\/zumo-de-apio-propiedades-cuidar-salud-visual\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.clinicabaviera.com\/blog\/zumo-de-apio-propiedades-cuidar-salud-visual\/#primaryimage","url":"https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/2019\/09\/apio.jpg","contentUrl":"https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/2019\/09\/apio.jpg","width":1250,"height":833,"caption":"Apio y zumo de apio"},{"@type":"BreadcrumbList","@id":"https:\/\/www.clinicabaviera.com\/blog\/zumo-de-apio-propiedades-cuidar-salud-visual\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.clinicabaviera.com\/blog\/"},{"@type":"ListItem","position":2,"name":"\u00bfPor qu\u00e9 el zumo de apio ayuda a cuidar la vista?"}]},{"@type":"WebSite","@id":"https:\/\/www.clinicabaviera.com\/blog\/#website","url":"https:\/\/www.clinicabaviera.com\/blog\/","name":"Blog de Baviera antes Cl\u00ednica Baviera","description":"Informaci\u00f3n sobre la salud visual","publisher":{"@id":"https:\/\/www.clinicabaviera.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.clinicabaviera.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.clinicabaviera.com\/blog\/#organization","name":"Blog de Baviera antes Cl\u00ednica Baviera","url":"https:\/\/www.clinicabaviera.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.clinicabaviera.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/2021\/02\/logo.png","contentUrl":"https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/2021\/02\/logo.png","width":526,"height":164,"caption":"Blog de Baviera antes Cl\u00ednica Baviera"},"image":{"@id":"https:\/\/www.clinicabaviera.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CLINICABAVIERA"]},{"@type":"Person","@id":"https:\/\/www.clinicabaviera.com\/blog\/#\/schema\/person\/3a838782fb6ef3b012ece10596a57a87","name":"Dr. Jose Ignacio Valls","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.clinicabaviera.com\/blog\/wp-content\/uploads\/2022\/12\/Dr.-Jose-Ignacio-Valls-min.jpg3d11b8dec63bd5761f7b945285fd4a5b","url":"https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/2022\/12\/Dr.-Jose-Ignacio-Valls-min.jpg","contentUrl":"https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/2022\/12\/Dr.-Jose-Ignacio-Valls-min.jpg","caption":"Dr. Jose Ignacio Valls"},"description":"El Dr. Jos\u00e9 Ignacio Valls es oftalm\u00f3logo especialista en cirug\u00eda refractiva, cirug\u00eda de la presbicia y cataratas. Desarrolla su labor asistencial en Baviera Alicante y Baviera Elche.","sameAs":["https:\/\/www.clinicabaviera.com\/clinica-oftalmologica-medico\/jose-ignacio-valls"],"url":"https:\/\/www.clinicabaviera.com\/clinica-oftalmologica-medico\/jose-ignacio-valls"}]}},"jetpack_featured_media_url":"https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/2019\/09\/apio.jpg","jetpack_shortlink":"https:\/\/wp.me\/p3aNmD-2DF","jetpack_sharing_enabled":true,"authors":[{"term_id":2261,"user_id":35,"is_guest":0,"slug":"dr-jose-ignacio-valls","display_name":"Dr. Jos\u00e9 Ignacio Valls","avatar_url":{"url":"https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/2022\/12\/Dr.-Jose-Ignacio-Valls-min.jpg","url2x":"https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/2022\/12\/Dr.-Jose-Ignacio-Valls-min.jpg"},"author_category":"","user_url":"https:\/\/www.clinicabaviera.com\/clinica-oftalmologica-medico\/jose-ignacio-valls","last_name":"Valls","first_name":"Jos\u00e9 Ignacio","job_title":"","description":"El Dr. Jos\u00e9 Ignacio Valls es oftalm\u00f3logo especialista en cirug\u00eda refractiva, cirug\u00eda de la presbicia y cataratas. Desarrolla su labor asistencial en Cl\u00ednica Baviera Alicante, Cl\u00ednica Baviera Elche y Cl\u00ednica Baviera Murcia."}],"_links":{"self":[{"href":"https:\/\/www.clinicabaviera.com\/blog\/wp-json\/wp\/v2\/posts\/10147","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.clinicabaviera.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.clinicabaviera.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.clinicabaviera.com\/blog\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/www.clinicabaviera.com\/blog\/wp-json\/wp\/v2\/comments?post=10147"}],"version-history":[{"count":20,"href":"https:\/\/www.clinicabaviera.com\/blog\/wp-json\/wp\/v2\/posts\/10147\/revisions"}],"predecessor-version":[{"id":36123,"href":"https:\/\/www.clinicabaviera.com\/blog\/wp-json\/wp\/v2\/posts\/10147\/revisions\/36123"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.clinicabaviera.com\/blog\/wp-json\/wp\/v2\/media\/27750"}],"wp:attachment":[{"href":"https:\/\/www.clinicabaviera.com\/blog\/wp-json\/wp\/v2\/media?parent=10147"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.clinicabaviera.com\/blog\/wp-json\/wp\/v2\/categories?post=10147"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.clinicabaviera.com\/blog\/wp-json\/wp\/v2\/tags?post=10147"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.clinicabaviera.com\/blog\/wp-json\/wp\/v2\/ppma_author?post=10147"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}