{"id":5421,"date":"2022-06-30T08:00:13","date_gmt":"2022-06-30T06:00:13","guid":{"rendered":"https:\/\/www.clinicabaviera.com\/blog\/?p=5421"},"modified":"2025-02-24T16:59:21","modified_gmt":"2025-02-24T15:59:21","slug":"falsos-mitos-curar-miopia-ejercicios","status":"publish","type":"post","link":"https:\/\/www.clinicabaviera.com\/blog\/bye-bye-gafas\/falsos-mitos-curar-miopia-con-ejercicios\/","title":{"rendered":"Falsos mitos: curar miop\u00eda con ejercicios"},"content":{"rendered":"\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-left kksr-valign-top\"\n    data-payload='{&quot;align&quot;:&quot;left&quot;,&quot;id&quot;:&quot;5421&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;top&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;680&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;4.7&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;4&quot;,&quot;greet&quot;:&quot;Rate this post&quot;,&quot;legend&quot;:&quot;4.7\\\/5 - (680 votos)&quot;,&quot;size&quot;:&quot;15&quot;,&quot;title&quot;:&quot;Falsos mitos: curar miop\u00eda con ejercicios&quot;,&quot;width&quot;:&quot;87.3&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 87.3px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 12px;\">\n            4.7\/5 - (680 votos)    <\/div>\n    <\/div>\n<p><span style=\"font-weight: 400;\">Los <\/span><b>ejercicios para curar la miop\u00eda<\/b><span style=\"font-weight: 400;\"> son, sencillamente, una falsedad, ya que la <a href=\"https:\/\/www.clinicabaviera.com\/refractiva-miopia\">miop\u00eda<\/a> se produce por un defecto en la forma del ojo del paciente. La miop\u00eda es una enfermedad causada por una mala refracci\u00f3n de la luz sobre la retina y, si queremos corregirla, es necesario tratar el problema de refracci\u00f3n que la causa.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Sin embargo, aunque no se puede curar la miop\u00eda naturalmente, s\u00ed que existen varias soluciones que nos pueden permitir corregirla y ver correctamente. <\/span><\/p>\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_86 ez-toc-wrap-center counter-hierarchy ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">\u00cdndice<\/p>\n<span class=\"ez-toc-title-toggle\"><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.clinicabaviera.com\/blog\/bye-bye-gafas\/falsos-mitos-curar-miopia-con-ejercicios\/#%C2%BFSe_puede_curar_la_miopia\" >\u00bfSe puede curar la miop\u00eda?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.clinicabaviera.com\/blog\/bye-bye-gafas\/falsos-mitos-curar-miopia-con-ejercicios\/#%C2%BFLos_ejercicios_visuales_son_recomendables_y_beneficiosos\" >\u00bfLos ejercicios visuales son recomendables y beneficiosos?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.clinicabaviera.com\/blog\/bye-bye-gafas\/falsos-mitos-curar-miopia-con-ejercicios\/#%C2%BFComo_se_corrige_la_miopia_con_cirugia_refractiva\" >\u00bfC\u00f3mo se corrige la miop\u00eda con cirug\u00eda refractiva?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.clinicabaviera.com\/blog\/bye-bye-gafas\/falsos-mitos-curar-miopia-con-ejercicios\/#%C2%BFQue_hacer_para_curar_la_miopia_sin_operaciones\" >\u00bfQu\u00e9 hacer para curar la miop\u00eda sin operaciones?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/www.clinicabaviera.com\/blog\/bye-bye-gafas\/falsos-mitos-curar-miopia-con-ejercicios\/#Fuentes\" >Fuentes<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"%C2%BFSe_puede_curar_la_miopia\"><\/span><span style=\"font-weight: 400;\">\u00bfSe puede curar la miop\u00eda?<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"font-weight: 400;\">La manera en la que se refracta la luz en la retina depende de la forma del ojo. Pero la forma del ojo no se puede cambiar haciendo ning\u00fan ejercicio, independientemente de lo que aseguran algunas informaciones que podemos encontrar en internet.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Las personas que afirman que se puede curar la miop\u00eda con ejercicios defienden que esta est\u00e1 causada por el estr\u00e9s, malos h\u00e1bitos o el exceso de esfuerzo. Estas afirmaciones son err\u00f3neas.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Adem\u00e1s, hay que tener en cuenta que algunos de estos m\u00e9todos son in\u00fatiles pero inofensivos, mientras que otros son realmente peligrosos y ponen en serio riesgo la salud visual de la persona que los practica.\u00a0<\/span><\/p>\n<p><a href=\"https:\/\/cloud.info.clinicabaviera.com\/adios-miedos\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-35916 size-full\" src=\"https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/2023\/10\/Adios_Gafas_Horizontal-1.jpg\" alt=\"\" width=\"751\" height=\"367\" srcset=\"https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/2023\/10\/Adios_Gafas_Horizontal-1.jpg 751w, https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/2023\/10\/Adios_Gafas_Horizontal-1-300x147.jpg 300w, https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/2023\/10\/Adios_Gafas_Horizontal-1-200x98.jpg 200w\" sizes=\"auto, (max-width: 751px) 100vw, 751px\" \/><\/a><\/p>\n<p><span style=\"font-weight: 400;\">Por lo tanto, la miop\u00eda no se pueden prevenir ni curar, aunque s\u00ed <\/span><span style=\"font-weight: 400;\">se puede corregir mediante distintos m\u00e9todos:\u00a0<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Uso de gafas<\/b><span style=\"font-weight: 400;\">: el cristal de las gafas modifica la forma en que la luz llega a la retina. Esto permite que, usando la graduaci\u00f3n correcta, la persona con miop\u00eda vea de forma clara y con nitidez.\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Uso de lentillas<\/b><span style=\"font-weight: 400;\">: el sistema de las lentillas es exactamente igual que el de las gafas. La \u00fanica diferencia consiste en que el cristal que modifica la forma en la que la luz llega a la retina se coloca directamente sobre la superficie del ojo.\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><a href=\"https:\/\/www.clinicabaviera.com\/cirugia-refractiva\"><b>Cirug\u00eda refractiva<\/b><\/a><span style=\"font-weight: 400;\">: la cirug\u00eda refractiva modifica la superficie del ojo y la adapta para que haga el mismo efecto que los cristales de las gafas y corrija la forma en la que la luz llega hasta la retina. De esta forma, se consigue corregir el defecto de refracci\u00f3n sin necesidad de tener que utilizar gafas o lentillas.<\/span><\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"%C2%BFLos_ejercicios_visuales_son_recomendables_y_beneficiosos\"><\/span><span style=\"font-weight: 400;\">\u00bfLos ejercicios visuales son recomendables y beneficiosos?<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Aunque no existen ejercicios para la vista que sean efectivos para corregir o mejorar la miop\u00eda, ni ning\u00fan otro defecto refractivo, s\u00ed que son recomendables y beneficiosos para relajar los ojos y aliviar molestias como la <\/span><a href=\"https:\/\/www.clinicabaviera.com\/blog\/bye-bye-gafasconoce-tus-ojosconoce-los-sintomas-de-los-ojos-cansados\/\"><span style=\"font-weight: 400;\">fatiga ocular<\/span><\/a><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por lo general, los principales beneficios de los ejercicios visuales son:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Relajar los ojos.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Prevenir o mejorar la fatiga visual.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Mejorar algunas molestias provocadas por el <\/span><a href=\"https:\/\/www.clinicabaviera.com\/ojo-seco\"><span style=\"font-weight: 400;\">ojo seco<\/span><\/a><span style=\"font-weight: 400;\">.<\/span><\/li>\n<\/ul>\n<h3><span style=\"font-weight: 400;\">Ejemplos de ejercicios visuales<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Los ejercicios oculares o de gimnasia visual se caracterizan por ser sencillos y r\u00e1pidos de realizar.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Algunos ejemplos de ejercicios visuales son los siguientes:\u00a0<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Parpadeos voluntarios<\/b><span style=\"font-weight: 400;\">: b\u00e1sicamente se trata de parpadear de forma r\u00e1pida a menudo y tambi\u00e9n cerrar los ojos y despegarlos suavemente en series de ejercicios de entre 5 y 10 repeticiones.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Palmeo de los ojos<\/b><span style=\"font-weight: 400;\">: nos sentamos relajadamente y nos tapamos los ojos con la palma de la mano ligeramente ahuecada, sin llegar a presionarlos. A continuaci\u00f3n, colocamos los dedos de una mano encima de la otra, sobre la frente. El siguiente paso consiste en respirar profundamente, imaginando que los ojos est\u00e1n tambi\u00e9n respirando. El objetivo de este ejercicio es relajar tanto los ojos como el resto del cuerpo.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Cambios de mirada<\/b><span style=\"font-weight: 400;\">: abrimos los ojos y dirigimos\u00a0 la mirada arriba y abajo, a derecha e izquierda y en c\u00edrculos, y luego repetimos el ejercicio con los ojos cerrados.\u00a0 Otro ejercicio consiste en coger dos l\u00e1pices, uno con cada mano, estirar los brazos e ir alternando la mirada de uno a otro, repitiendo este movimiento unas 10 veces.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Cerrar y abrir los ojos<\/b><span style=\"font-weight: 400;\">: es muy f\u00e1cil, solo hay que abrir y cerrar los ojos fuertemente en intervalos de 3-5 segundos y repetir el ejercicio 7 u 8 veces.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Masaje en los ojos<\/b><span style=\"font-weight: 400;\">: con los ojos cerrados, los vamos masajeando suavemente con 3 dedos, ejerciendo una leve presi\u00f3n sobre los p\u00e1rpados. Lo recomendable es repetir la operaci\u00f3n unas 5 veces en intervalos cortos de unos 3-5 segundos.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Ejercicios de enfoque<\/b><span style=\"font-weight: 400;\">: la idea de este ejercicio es concentrarte e ir cambiando el enfoque de la mirada entre objetos cercanos y objetos lejanos.\u00a0<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Insistimos en que por muchos ejercicios de ojos que se hagan, la miop\u00eda seguir\u00e1 ah\u00ed. Ning\u00fan oftalm\u00f3logo te dir\u00e1 que es posible curar la miop\u00eda ni ning\u00fan problema refractivo haciendo ejercicios.<\/span><\/p>\n<h2><span class=\"ez-toc-section\" id=\"%C2%BFComo_se_corrige_la_miopia_con_cirugia_refractiva\"><\/span><span style=\"font-weight: 400;\">\u00bfC\u00f3mo se corrige la miop\u00eda con cirug\u00eda refractiva?<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"font-weight: 400;\">La miop\u00eda puede corregirse con diferentes t\u00e9cnicas de cirug\u00eda l\u00e1ser: <\/span><a href=\"https:\/\/www.clinicabaviera.com\/lasik\"><span style=\"font-weight: 400;\">Lasik <\/span><\/a><span style=\"font-weight: 400;\">o <\/span><a href=\"https:\/\/www.clinicabaviera.com\/lasek\"><span style=\"font-weight: 400;\">t\u00e9cnicas de superficie PRK\/LASEK)<\/span><\/a><span style=\"font-weight: 400;\"> o mediante la <\/span><a href=\"https:\/\/www.clinicabaviera.com\/cirugia-refractiva-altas-graduaciones\"><span style=\"font-weight: 400;\">implantaci\u00f3n de una lente intraocular. <\/span><\/a><span style=\"font-weight: 400;\">Debe ser el oftalm\u00f3logo el que elija la mejor opci\u00f3n quir\u00fargica en funci\u00f3n de las caracter\u00edsticas fisiol\u00f3gicas de cada paciente.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La t\u00e9cnica m\u00e1s extendida y con mayor consolidaci\u00f3n tras m\u00e1s de 20 a\u00f1os de aplicaci\u00f3n es la t\u00e9cnica Lasik. Se trata de una intervenci\u00f3n sencilla, r\u00e1pida y segura que permite al paciente reincorporarse a su vida habitual en un breve espacio de tiempo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La intervenci\u00f3n se realiza de manera ambulatoria y con anestesia local y el paciente puede volver a casa el mismo d\u00eda de la operaci\u00f3n y por su propio pie.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Los pasos de la cirug\u00eda refractiva para curar la miop\u00eda con la t\u00e9cnica Lasik son los siguientes:\u00a0<\/span><\/p>\n<ol>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">El cirujano levanta una fina capa del epitelio corneal, que es la capa m\u00e1s superficial de la c\u00f3rnea, y deja al descubierto la zona en la cual se aplica el l\u00e1ser. Este paso es diferente en las t\u00e9cnicas de superficie.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">A continuaci\u00f3n se aplica el l\u00e1ser durante unos segundos. El l\u00e1ser est\u00e1 programado de manera personalizada con los datos de cada paciente y cuenta con un sistema de seguridad que controla los movimientos del ojo para evitar que se aplique en una zona incorrecta.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Finalmente se recoloca el tejido corneal que se adhiere sin necesidad de puntos de sutura. El proceso total no dura m\u00e1s de diez minutos<\/span><\/li>\n<\/ol>\n<p><span style=\"font-weight: 400;\">Debido a su sencillez, la cirug\u00eda l\u00e1ser es la primera opci\u00f3n cuando hablamos de cirug\u00eda refractiva. Sin embargo, tambi\u00e9n existe la posibilidad de implantar una lente intraocular en los casos en los que, debido a las caracter\u00edsticas del ojo del paciente, no se pueda practicar la cirug\u00eda l\u00e1ser.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La elecci\u00f3n de la opci\u00f3n m\u00e1s adecuada es determinada por los oftalm\u00f3logos despu\u00e9s de un estudio exhaustivo que se realiza durante una <\/span><a href=\"https:\/\/www.clinicabaviera.com\/cirugia-refractiva-primera-consulta\"><span style=\"font-weight: 400;\">primera consulta preoperatoria<\/span><\/a><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-5397 size-full\" src=\"https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/2016\/06\/iStock_82184141_SMALL.jpg\" alt=\"Chica con gafas se hace una pregunta\" width=\"802\" height=\"597\" srcset=\"https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/2016\/06\/iStock_82184141_SMALL.jpg 802w, https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/2016\/06\/iStock_82184141_SMALL-200x149.jpg 200w, https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/2016\/06\/iStock_82184141_SMALL-300x223.jpg 300w, https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/2016\/06\/iStock_82184141_SMALL-768x572.jpg 768w, https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/2016\/06\/iStock_82184141_SMALL-650x484.jpg 650w\" sizes=\"auto, (max-width: 802px) 100vw, 802px\" \/><\/p>\n<h2><span class=\"ez-toc-section\" id=\"%C2%BFQue_hacer_para_curar_la_miopia_sin_operaciones\"><\/span><span style=\"font-weight: 400;\">\u00bfQu\u00e9 hacer para curar la miop\u00eda sin operaciones?<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Si no se quiere pasar por una operaci\u00f3n de miop\u00eda, se puede optar por el uso de gafas o lentillas para corregir este problema visual. En ambos casos, esto permite corregir la miop\u00eda gracias a que tanto las gafas como las lentillas modifican la forma en la que la luz llega a la retina. Utilizando la graduaci\u00f3n adecuada, se consigue que el paciente vea correctamente.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">No obstante, en estos casos, el paciente siempre depender\u00e1 del uso de las gafas o las lentillas para ver bien.\u00a0<\/span><\/p>\n<h2><span class=\"ez-toc-section\" id=\"Fuentes\"><\/span><span style=\"font-weight: 400;\">Fuentes<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<ul>\n<li><a href=\"https:\/\/www.aao.org\/salud-ocular\/enfermedades\/miopia\" rel=\"nofollow\">Academia Americana de Oftalmolog\u00eda (AAO) &#8211; Visi\u00f3n de cerca: \u00bfQu\u00e9 es la miop\u00eda?<\/a><\/li>\n<li><a href=\"https:\/\/www.aao.org\/salud-ocular\/tratamientos\/cirugia-refractiva\" rel=\"nofollow\">Academia Americana de Oftalmolog\u00eda (AAO) &#8211; \u00bfQu\u00e9 es la cirug\u00eda refractiva?<\/a><\/li>\n<li><a href=\"https:\/\/www.aao.org\/salud-ocular\/tratamientos\/lasik-cirugia-ocular-con-laser\" rel=\"nofollow\">Academia Americana de Oftalmolog\u00eda (AAO) &#8211; LASIK- Cirug\u00eda ocular con l\u00e1ser<\/a><\/li>\n<\/ul>\n<hr \/>\n<pre class=\"ti-widget\" style=\"display: none\"><template id=\"trustindex-google-widget-html\"><div class=\" ti-widget  ti-goog ti-review-text-mode-readmore ti-text-align-left\" data-no-translation=\"true\" data-plugin-version=\"13.3.2\" data-layout-id=\"5\" data-layout-category=\"slider\" data-set-id=\"light-minimal\" data-pid=\"\" data-language=\"es\" data-close-locale=\"Cerca\" data-review-target-width=\"275\" data-css-version=\"2\" data-reply-by-locale=\"Respuesta del propietario\" data-only-rating-locale=\"Este usuario solo dej\u00f3 una calificaci\u00f3n.\" data-pager-autoplay-timeout=\"6\"> <div class=\"ti-widget-container ti-col-4\"> <div class=\"ti-footer ti-footer-grid source-Google\"> <div class=\"ti-fade-container\"> <div class=\"ti-rating-text\"> <strong class=\"ti-rating ti-rating-large\"> EXCELENTE <\/strong> <\/div> <span class=\"ti-stars star-lg\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><\/span> <div class=\"ti-rating-text\"> <span class=\"nowrap\">A base de <strong>570 rese\u00f1as<\/strong><\/span> <\/div> <div class=\"ti-large-logo\"> <div class=\"ti-v-center\"> <trustindex-image class=\"ti-logo-fb\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/logo.svg\" width=\"150\" height=\"25\" loading=\"lazy\" alt=\"Google\"><\/trustindex-image> <\/div> <\/div> <\/div> <\/div> <div class=\"ti-reviews-container\"> <div class=\"ti-controls\"> <div class=\"ti-next\" aria-label=\"Siguiente rese\u00f1a\" role=\"button\" tabindex=\"0\"><\/div> <div class=\"ti-prev\" aria-label=\"Rese\u00f1a anterior\" role=\"button\" tabindex=\"0\"><\/div> <\/div> <div class=\"ti-reviews-container-wrapper\">  <div data-empty=\"0\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-time=\"\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publicado en Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocKWHKmwDoN8jelN8JHWQw2buiU4ji6WyuVq8pcV4kRI=w40-h40-c-rp-mo-br100\" alt=\"Karelys Asencio Torres profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Karelys Asencio Torres <\/div> <div class=\"ti-date\">05\/03\/2024<\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex verifica que la fuente original de la rese\u00f1a sea Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Esta cl\u00ednica sin duda es la mejor !! El trato en recepci\u00f3n y de los m\u00e9dicos es excepcional. Estoy muy contenta con los resultados. Muchas gracias !<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Ocultar\" data-open-text=\"Leer m\u00e1s\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-time=\"\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publicado en Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocJx5lc8VzH_Kx5vNl4iC9Qof6IGYcXj03vtn_CJ67tj=w40-h40-c-rp-mo-br100\" alt=\"Vanesa Delgado Arcos profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Vanesa Delgado Arcos <\/div> <div class=\"ti-date\">01\/03\/2024<\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex verifica que la fuente original de la rese\u00f1a sea Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Much\u00edsima profesionalidad por parte de todo el equipo desde recepci\u00f3n y por supuesto si doctor.Estoy totalmente complacida por el resultado de la operaci\u00f3n y posteriores seguimientos.100%recomendable.<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Ocultar\" data-open-text=\"Leer m\u00e1s\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-time=\"\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publicado en Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjViSSX9rp-UKWvltgBF-J8MwK4Ga5nbJvaYsl3jYkAh2LQ=w40-h40-c-rp-mo-br100\" alt=\"Jorge Carnicero profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Jorge Carnicero <\/div> <div class=\"ti-date\">27\/02\/2024<\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex verifica que la fuente original de la rese\u00f1a sea Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Me oper\u00e9 ya hace un mes con laser de miop\u00eda y no pude tomar mejor decisi\u00f3n, buen asesoramiento desde el principio, un equipo maravilloso que est\u00e1n disponibles para cualquier consulta y unos resultados \u00f3ptimos, sensaci\u00f3n inmejorable poder ver otra vez perfectamente sin necesidad de gafas.<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Ocultar\" data-open-text=\"Leer m\u00e1s\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-time=\"\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publicado en Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocLf5YTDoqTOI9RiEgIqmgY0sL1jjWzGDFlZUKGefO3E=w40-h40-c-rp-mo-br100\" alt=\"Carlos \u00c1ngel P\u00e9rez profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Carlos \u00c1ngel P\u00e9rez <\/div> <div class=\"ti-date\">27\/02\/2024<\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex verifica que la fuente original de la rese\u00f1a sea Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Atenci\u00f3n muy buena de la doctora y de las auxiliares<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Ocultar\" data-open-text=\"Leer m\u00e1s\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-time=\"\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publicado en Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocLJ9j-vNwboPm0yglVXrs4FTPEon3Om3ZTJi7xaqcjl=w40-h40-c-rp-mo-br100\" alt=\"Virginia Jimenez profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Virginia Jimenez <\/div> <div class=\"ti-date\">22\/02\/2024<\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex verifica que la fuente original de la rese\u00f1a sea Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->He recibido un trato espectacular por parte de todos los trabajadores de la cl\u00ednica de M\u00f3stoles.\nLa operaci\u00f3n me la realiz\u00f3 el doctor Rafael, y sali\u00f3 todo muy muy bien me operado de miop\u00eda y astigmatismo, y el mismo d\u00eda por la noche ya pod\u00eda ver y hacer vida normal. Lo recomiendo 100 por 100.\nLlegue con miedo por que la vista es algo muy delicado y a d\u00eda de hoy la mejor decisi\u00f3n que tom\u00e9 fue quitarme las gafas y hacerlo con ellos.\n\nGracias<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Ocultar\" data-open-text=\"Leer m\u00e1s\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-time=\"\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publicado en Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjVdbd3Sm-F_C3qjnSPIEeZ28H3K404OeYdISk2TIzCrhH0=w40-h40-c-rp-mo-ba2-br100\" alt=\"Isidro Hoyas profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Isidro Hoyas <\/div> <div class=\"ti-date\">20\/02\/2024<\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex verifica que la fuente original de la rese\u00f1a sea Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Buenos profesionales y las chicas muy amables y atentas<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Ocultar\" data-open-text=\"Leer m\u00e1s\"><\/span> <\/div> <\/div>  <\/div> <div class=\"ti-controls-line\"> <div class=\"dot\"><\/div> <\/div>   <\/div> <\/div> <\/div> <\/template><\/pre><div data-src=\"https:\/\/cdn.trustindex.io\/loader.js?wp-widget\" data-template-id=\"trustindex-google-widget-html\" data-css-url=\"https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/trustindex-google-widget.css?1787550621\"><\/div>\n<hr \/>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los ejercicios para curar la miop\u00eda son, sencillamente, una falsedad, ya que la miop\u00eda se produce por un defecto en la forma del ojo del paciente. La miop\u00eda es una enfermedad causada por una mala refracci\u00f3n de la luz sobre la retina y, si queremos corregirla, es necesario tratar el problema de refracci\u00f3n que la [&hellip;]<\/p>\n","protected":false},"author":36,"featured_media":5397,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1146],"tags":[1304,963,19],"ppma_author":[2262],"class_list":["post-5421","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vive-la-vida-sin-gafas","tag-curar","tag-ejercicios","tag-miopia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Falsos mitos: curar miop\u00eda con ejercicios - Blog de Baviera antes Cl\u00ednica Baviera<\/title>\n<meta name=\"description\" content=\"Hay quienes afirman poder curar miop\u00eda con ejercicios oculares. Curar miopia con ejercicios es imposible, en este art\u00edculo explicamos por qu\u00e9\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.clinicabaviera.com\/blog\/bye-bye-gafas\/falsos-mitos-curar-miopia-con-ejercicios\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Falsos mitos: curar miop\u00eda con ejercicios - Blog de Baviera antes Cl\u00ednica Baviera\" \/>\n<meta property=\"og:description\" content=\"Hay quienes afirman poder curar miop\u00eda con ejercicios oculares. Curar miopia con ejercicios es imposible, en este art\u00edculo explicamos por qu\u00e9\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.clinicabaviera.com\/blog\/bye-bye-gafas\/falsos-mitos-curar-miopia-con-ejercicios\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog de Baviera antes Cl\u00ednica Baviera\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CLINICABAVIERA\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-30T06:00:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-24T15:59:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/2016\/06\/iStock_82184141_SMALL.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"802\" \/>\n\t<meta property=\"og:image:height\" content=\"597\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dr. Fernando Llovet\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dr. Fernando Llovet\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Falsos mitos: curar miop\u00eda con ejercicios - Blog de Baviera antes Cl\u00ednica Baviera","description":"Hay quienes afirman poder curar miop\u00eda con ejercicios oculares. Curar miopia con ejercicios es imposible, en este art\u00edculo explicamos por qu\u00e9","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.clinicabaviera.com\/blog\/bye-bye-gafas\/falsos-mitos-curar-miopia-con-ejercicios\/","og_locale":"es_ES","og_type":"article","og_title":"Falsos mitos: curar miop\u00eda con ejercicios - Blog de Baviera antes Cl\u00ednica Baviera","og_description":"Hay quienes afirman poder curar miop\u00eda con ejercicios oculares. Curar miopia con ejercicios es imposible, en este art\u00edculo explicamos por qu\u00e9","og_url":"https:\/\/www.clinicabaviera.com\/blog\/bye-bye-gafas\/falsos-mitos-curar-miopia-con-ejercicios\/","og_site_name":"Blog de Baviera antes Cl\u00ednica Baviera","article_publisher":"https:\/\/www.facebook.com\/CLINICABAVIERA","article_published_time":"2022-06-30T06:00:13+00:00","article_modified_time":"2025-02-24T15:59:21+00:00","og_image":[{"width":802,"height":597,"url":"https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/2016\/06\/iStock_82184141_SMALL.jpg","type":"image\/jpeg"}],"author":"Dr. Fernando Llovet","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Dr. Fernando Llovet","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.clinicabaviera.com\/blog\/bye-bye-gafas\/falsos-mitos-curar-miopia-con-ejercicios\/#article","isPartOf":{"@id":"https:\/\/www.clinicabaviera.com\/blog\/bye-bye-gafas\/falsos-mitos-curar-miopia-con-ejercicios\/"},"author":{"name":"Dr. Fernando Llovet","@id":"https:\/\/www.clinicabaviera.com\/blog\/#\/schema\/person\/6f99a3c85c06ce9bae3b6bdff6094074"},"headline":"Falsos mitos: curar miop\u00eda con ejercicios","datePublished":"2022-06-30T06:00:13+00:00","dateModified":"2025-02-24T15:59:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.clinicabaviera.com\/blog\/bye-bye-gafas\/falsos-mitos-curar-miopia-con-ejercicios\/"},"wordCount":1292,"commentCount":25,"publisher":{"@id":"https:\/\/www.clinicabaviera.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.clinicabaviera.com\/blog\/bye-bye-gafas\/falsos-mitos-curar-miopia-con-ejercicios\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/2016\/06\/iStock_82184141_SMALL.jpg","keywords":["curar","ejercicios","miopia"],"articleSection":["Vive la vida sin gafas"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.clinicabaviera.com\/blog\/bye-bye-gafas\/falsos-mitos-curar-miopia-con-ejercicios\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.clinicabaviera.com\/blog\/bye-bye-gafas\/falsos-mitos-curar-miopia-con-ejercicios\/","url":"https:\/\/www.clinicabaviera.com\/blog\/bye-bye-gafas\/falsos-mitos-curar-miopia-con-ejercicios\/","name":"Falsos mitos: curar miop\u00eda con ejercicios - Blog de Baviera antes Cl\u00ednica Baviera","isPartOf":{"@id":"https:\/\/www.clinicabaviera.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.clinicabaviera.com\/blog\/bye-bye-gafas\/falsos-mitos-curar-miopia-con-ejercicios\/#primaryimage"},"image":{"@id":"https:\/\/www.clinicabaviera.com\/blog\/bye-bye-gafas\/falsos-mitos-curar-miopia-con-ejercicios\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/2016\/06\/iStock_82184141_SMALL.jpg","datePublished":"2022-06-30T06:00:13+00:00","dateModified":"2025-02-24T15:59:21+00:00","description":"Hay quienes afirman poder curar miop\u00eda con ejercicios oculares. Curar miopia con ejercicios es imposible, en este art\u00edculo explicamos por qu\u00e9","breadcrumb":{"@id":"https:\/\/www.clinicabaviera.com\/blog\/bye-bye-gafas\/falsos-mitos-curar-miopia-con-ejercicios\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.clinicabaviera.com\/blog\/bye-bye-gafas\/falsos-mitos-curar-miopia-con-ejercicios\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.clinicabaviera.com\/blog\/bye-bye-gafas\/falsos-mitos-curar-miopia-con-ejercicios\/#primaryimage","url":"https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/2016\/06\/iStock_82184141_SMALL.jpg","contentUrl":"https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/2016\/06\/iStock_82184141_SMALL.jpg","width":802,"height":597,"caption":"Chica con gafas se hace una pregunta"},{"@type":"BreadcrumbList","@id":"https:\/\/www.clinicabaviera.com\/blog\/bye-bye-gafas\/falsos-mitos-curar-miopia-con-ejercicios\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.clinicabaviera.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Falsos mitos: curar miop\u00eda con ejercicios"}]},{"@type":"WebSite","@id":"https:\/\/www.clinicabaviera.com\/blog\/#website","url":"https:\/\/www.clinicabaviera.com\/blog\/","name":"Blog de Baviera antes Cl\u00ednica Baviera","description":"Informaci\u00f3n sobre la salud visual","publisher":{"@id":"https:\/\/www.clinicabaviera.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.clinicabaviera.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.clinicabaviera.com\/blog\/#organization","name":"Baviera","url":"https:\/\/www.clinicabaviera.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.clinicabaviera.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/2021\/02\/logo.png","contentUrl":"https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/2021\/02\/logo.png","width":526,"height":164,"caption":"Baviera"},"image":{"@id":"https:\/\/www.clinicabaviera.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CLINICABAVIERA"]},{"@type":"Person","@id":"https:\/\/www.clinicabaviera.com\/blog\/#\/schema\/person\/6f99a3c85c06ce9bae3b6bdff6094074","name":"Dr. Fernando Llovet","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.clinicabaviera.com\/blog\/wp-content\/uploads\/2022\/07\/fernando_llovet_valencia_1-2-scaled.jpg8676b0fc3d378e07f4060734118f7d9c","url":"https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/2022\/07\/fernando_llovet_valencia_1-2-scaled.jpg","contentUrl":"https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/2022\/07\/fernando_llovet_valencia_1-2-scaled.jpg","caption":"Dr. Fernando Llovet"},"description":"El Dr. Fernando Llovet es oftalm\u00f3logo especialista en cirug\u00eda refractiva, cirug\u00eda de la presbicia y cataratas. Adem\u00e1s, es co-fundador de Baviera. Desarrolla su labor asistencial en Baviera Madrid y Baviera Valencia.","sameAs":["https:\/\/www.clinicabaviera.com\/clinica-oftalmologica-medico\/fernando-llovet"],"url":"https:\/\/www.clinicabaviera.com\/clinica-oftalmologica-medico\/fernando-llovet"}]}},"jetpack_shortlink":"https:\/\/wp.me\/p3aNmD-1pr","jetpack_sharing_enabled":true,"authors":[{"term_id":2262,"user_id":36,"is_guest":0,"slug":"dr-fernando-llovet","display_name":"Dr. Fernando Llovet","avatar_url":{"url":"https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/2022\/07\/fernando_llovet_valencia_1-2-scaled.jpg","url2x":"https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/2022\/07\/fernando_llovet_valencia_1-2-scaled.jpg"},"author_category":"","user_url":"https:\/\/www.clinicabaviera.com\/clinica-oftalmologica-medico\/fernando-llovet","last_name":"Llovet","first_name":"Fernando","job_title":"","description":"El Dr. Fernando Llovet es oftalm\u00f3logo especialista en cirug\u00eda refractiva, cirug\u00eda de la presbicia y cataratas. Adem\u00e1s, es co-fundador de Cl\u00ednica Baviera. Desarrolla su labor asistencial en Cl\u00ednica Baviera Madrid y Cl\u00ednica Baviera Valencia."}],"jetpack_featured_media_url":"https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/2016\/06\/iStock_82184141_SMALL.jpg","_links":{"self":[{"href":"https:\/\/www.clinicabaviera.com\/blog\/wp-json\/wp\/v2\/posts\/5421","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.clinicabaviera.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.clinicabaviera.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.clinicabaviera.com\/blog\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/www.clinicabaviera.com\/blog\/wp-json\/wp\/v2\/comments?post=5421"}],"version-history":[{"count":27,"href":"https:\/\/www.clinicabaviera.com\/blog\/wp-json\/wp\/v2\/posts\/5421\/revisions"}],"predecessor-version":[{"id":36096,"href":"https:\/\/www.clinicabaviera.com\/blog\/wp-json\/wp\/v2\/posts\/5421\/revisions\/36096"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.clinicabaviera.com\/blog\/wp-json\/wp\/v2\/media\/5397"}],"wp:attachment":[{"href":"https:\/\/www.clinicabaviera.com\/blog\/wp-json\/wp\/v2\/media?parent=5421"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.clinicabaviera.com\/blog\/wp-json\/wp\/v2\/categories?post=5421"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.clinicabaviera.com\/blog\/wp-json\/wp\/v2\/tags?post=5421"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.clinicabaviera.com\/blog\/wp-json\/wp\/v2\/ppma_author?post=5421"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}