{"id":7712,"date":"2023-03-01T08:00:56","date_gmt":"2023-03-01T06:00:56","guid":{"rendered":"https:\/\/www.clinicabaviera.com\/blog\/?p=7712"},"modified":"2025-02-13T13:27:07","modified_gmt":"2025-02-13T12:27:07","slug":"conjuntivitis-virica-tratamiento-recomendaciones","status":"publish","type":"post","link":"https:\/\/www.clinicabaviera.com\/blog\/conjuntivitis-virica-tratamiento-recomendaciones\/","title":{"rendered":"Conjuntivitis v\u00edrica: tratamiento y recomendaciones"},"content":{"rendered":"\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-left kksr-valign-top\"\n    data-payload='{&quot;align&quot;:&quot;left&quot;,&quot;id&quot;:&quot;7712&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;top&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;48&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;4.9&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;4&quot;,&quot;greet&quot;:&quot;Rate this post&quot;,&quot;legend&quot;:&quot;4.9\\\/5 - (48 votos)&quot;,&quot;size&quot;:&quot;15&quot;,&quot;title&quot;:&quot;Conjuntivitis v\u00edrica: tratamiento y recomendaciones&quot;,&quot;width&quot;:&quot;91.1&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 91.1px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 12px;\">\n            4.9\/5 - (48 votos)    <\/div>\n    <\/div>\n<p><span style=\"font-weight: 400;\">La <\/span><b>conjuntivitis v\u00edrica<\/b><span style=\"font-weight: 400;\"> es una de las afecciones oculares m\u00e1s comunes. Esta enfermedad aparece cuando uno o varios virus infectan la conjuntiva del ojo, la membrana m\u00e1s externa que recubre la superficie del ojo y el interior del p\u00e1rpado.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por suerte, con las precauciones y el tratamiento correspondiente, se trata de una infecci\u00f3n que puede curarse pasados unos pocos d\u00edas. <\/span><\/p>\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_86 ez-toc-wrap-center counter-hierarchy ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">\u00cdndice<\/p>\n<span class=\"ez-toc-title-toggle\"><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.clinicabaviera.com\/blog\/conjuntivitis-virica-tratamiento-recomendaciones\/#%C2%BFQue_es_la_conjuntivitis_virica\" >\u00bfQu\u00e9 es la conjuntivitis v\u00edrica?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.clinicabaviera.com\/blog\/conjuntivitis-virica-tratamiento-recomendaciones\/#%C2%BFLa_conjuntivitis_virica_es_contagiosa\" >\u00bfLa conjuntivitis v\u00edrica es contagiosa?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.clinicabaviera.com\/blog\/conjuntivitis-virica-tratamiento-recomendaciones\/#%C2%BFCuales_son_los_sintomas_de_la_conjuntivitis_virica\" >\u00bfCu\u00e1les son los s\u00edntomas de la conjuntivitis v\u00edrica?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.clinicabaviera.com\/blog\/conjuntivitis-virica-tratamiento-recomendaciones\/#%C2%BFCuanto_dura_la_conjuntivitis_virica\" >\u00bfCu\u00e1nto dura la conjuntivitis v\u00edrica?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/www.clinicabaviera.com\/blog\/conjuntivitis-virica-tratamiento-recomendaciones\/#%C2%BFComo_se_diagnostica\" >\u00bfC\u00f3mo se diagnostica?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/www.clinicabaviera.com\/blog\/conjuntivitis-virica-tratamiento-recomendaciones\/#%C2%BFCual_es_el_tratamiento_ideal_para_frenar_la_conjuntivitis_virica\" >\u00bfCu\u00e1l es el tratamiento ideal para frenar la conjuntivitis v\u00edrica?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/www.clinicabaviera.com\/blog\/conjuntivitis-virica-tratamiento-recomendaciones\/#%C2%BFCuales_son_las_recomendaciones_para_evitar_el_contagio_de_la_conjuntivitis_virica\" >\u00bfCu\u00e1les son las recomendaciones para evitar el contagio de la conjuntivitis v\u00edrica?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/www.clinicabaviera.com\/blog\/conjuntivitis-virica-tratamiento-recomendaciones\/#%C2%BFQue_medidas_de_proteccion_pueden_aplicarse_en_verano\" >\u00bfQu\u00e9 medidas de protecci\u00f3n pueden aplicarse en verano?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/www.clinicabaviera.com\/blog\/conjuntivitis-virica-tratamiento-recomendaciones\/#%C2%BFQue_complicaciones_puede_causar_la_conjuntivitis_virica\" >\u00bfQu\u00e9 complicaciones puede causar la conjuntivitis v\u00edrica?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/www.clinicabaviera.com\/blog\/conjuntivitis-virica-tratamiento-recomendaciones\/#%C2%BFComo_saber_si_la_conjuntivitis_es_bacteriana_o_viral\" >\u00bfC\u00f3mo saber si la conjuntivitis es bacteriana o viral?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/www.clinicabaviera.com\/blog\/conjuntivitis-virica-tratamiento-recomendaciones\/#%C2%BFCuando_ir_al_medico_por_una_conjuntivitis\" >\u00bfCu\u00e1ndo ir al m\u00e9dico por una conjuntivitis?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/www.clinicabaviera.com\/blog\/conjuntivitis-virica-tratamiento-recomendaciones\/#%C2%BFExiste_una_vacuna_para_prevenir_la_conjuntivitis\" >\u00bfExiste una vacuna para prevenir la conjuntivitis?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/www.clinicabaviera.com\/blog\/conjuntivitis-virica-tratamiento-recomendaciones\/#Fuentes\" >Fuentes<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"%C2%BFQue_es_la_conjuntivitis_virica\"><\/span><span style=\"font-weight: 400;\">\u00bfQu\u00e9 es la conjuntivitis v\u00edrica?<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"font-weight: 400;\">La conjuntivitis v\u00edrica es un tipo de <\/span><span style=\"font-weight: 400;\">conjuntivitis<\/span><span style=\"font-weight: 400;\"> que se caracteriza por estar causada por virus (a diferencia de otras conjuntivitis causadas por bacterias o al\u00e9rgenos).\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La conjuntivitis v\u00edrica produce:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Inflamaci\u00f3n de la conjuntiva.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Enrojecimiento.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Picor.\u00a0<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Aunque puede aparecer en cualquier momento del a\u00f1o, su presencia es m\u00e1s habitual durante el inicio de la estaci\u00f3n fr\u00eda (oto\u00f1o e invierno).\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-34143 size-full\" src=\"https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/2023\/06\/Conjuntivitis-scaled.jpg\" alt=\"\u00bfQu\u00e9 tipos de conjuntivitis existen?\" width=\"2560\" height=\"911\" srcset=\"https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/2023\/06\/Conjuntivitis-scaled.jpg 2560w, https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/2023\/06\/Conjuntivitis-300x107.jpg 300w, https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/2023\/06\/Conjuntivitis-840x299.jpg 840w, https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/2023\/06\/Conjuntivitis-200x71.jpg 200w, https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/2023\/06\/Conjuntivitis-768x273.jpg 768w, https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/2023\/06\/Conjuntivitis-1536x547.jpg 1536w, https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/2023\/06\/Conjuntivitis-2048x729.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/p>\n<h2><span class=\"ez-toc-section\" id=\"%C2%BFLa_conjuntivitis_virica_es_contagiosa\"><\/span><span style=\"font-weight: 400;\">\u00bfLa conjuntivitis v\u00edrica es contagiosa?<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>La conjuntivitis puede estar causada por virus, bacterias, alg\u00fan al\u00e9rgeno o por sustancias irritantes.<\/p>\n<ul>\n<li>Es muy contagiosa cuando se trata de una\u00a0conjuntivitis v\u00edrica o una conjuntivitis bacteriana y, por lo tanto, puede transmitirse f\u00e1cil y r\u00e1pidamente de un ojo a otro del mismo paciente o de una persona a otra.<\/li>\n<li>La conjuntivitis causada por al\u00e9rgenos (polvo, polen, pelo de animales\u2026) o por sustancias irritantes no es contagiosa, a menos que se produzca una infecci\u00f3n viral o bacteriana secundaria.<\/li>\n<\/ul>\n<p>En ocasiones, a los m\u00e9dicos les resulta muy complicado realizar un diagn\u00f3stico firme sobre el tipo de conjuntivitis que tiene el paciente. Por esta raz\u00f3n es necesario mantener ciertas medidas para prevenir el contagio de la conjuntivitis.<\/p>\n<p><a href=\"https:\/\/cloud.info.clinicabaviera.com\/ojo-con-tus-ojos\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-35824 size-full\" src=\"https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/2025\/01\/Ojo_con_tus_ojos_horizontal.jpg\" alt=\"\" width=\"751\" height=\"367\" srcset=\"https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/2025\/01\/Ojo_con_tus_ojos_horizontal.jpg 751w, https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/2025\/01\/Ojo_con_tus_ojos_horizontal-300x147.jpg 300w, https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/2025\/01\/Ojo_con_tus_ojos_horizontal-200x98.jpg 200w\" sizes=\"auto, (max-width: 751px) 100vw, 751px\" \/><\/a><\/p>\n<h2><span class=\"ez-toc-section\" id=\"%C2%BFCuales_son_los_sintomas_de_la_conjuntivitis_virica\"><\/span><span style=\"font-weight: 400;\">\u00bfCu\u00e1les son los s\u00edntomas de la conjuntivitis v\u00edrica?<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Los s\u00edntomas m\u00e1s comunes de la conjuntivitis v\u00edrica son los siguientes:\u00a0<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Picor o escozor en el ojo.\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Sensaci\u00f3n o necesidad de rascarse el ojo de forma continuada.\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Enrojecimiento de la parte blanca del ojo.\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Inflamaci\u00f3n del ojo.\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Lagrimeo m\u00e1s abundante de lo habitual.\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Inflamaci\u00f3n de los ganglios linf\u00e1ticos del cuello y detr\u00e1s de las orejas.\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">En algunos casos, fiebre.\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><a href=\"https:\/\/www.clinicabaviera.com\/blog\/bye-bye-gafas\/que-es-la-fotofobia\/\"><span style=\"font-weight: 400;\">Fotofobia<\/span><\/a><span style=\"font-weight: 400;\"> o sensibilidad a la luz.\u00a0<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Por lo general, los s\u00edntomas de la conjuntivitis v\u00edrica no son importantes y suelen desaparecer en una o, como mucho, dos semanas. Tampoco suele ser contagiosa a partir de las 24 horas tras haberse iniciado el tratamiento.\u00a0<\/span><\/p>\n<h2><span class=\"ez-toc-section\" id=\"%C2%BFCuanto_dura_la_conjuntivitis_virica\"><\/span><span style=\"font-weight: 400;\">\u00bfCu\u00e1nto dura la conjuntivitis v\u00edrica?<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Las molestias en los ojos, que se asemejan a un llanto constante y m\u00e1s espeso de lo normal, <\/span><a href=\"https:\/\/www.clinicabaviera.com\/blog\/cuanto-dura-la-conjuntivitis\/\"><span style=\"font-weight: 400;\">suelen durar entre 7 y 15 d\u00edas<\/span><\/a><span style=\"font-weight: 400;\">. Es decir, estamos hablando de una enfermedad cuyos s\u00edntomas desaparecen en unas 2 o 3 semanas y ante los cuales es necesario que sigamos el tratamiento que nos recomiende nuestro oftalm\u00f3logo.<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-31412 size-full\" src=\"https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/2019\/09\/iStock-1063894116.jpg\" alt=\"conjuntivitis v\u00edrica\" width=\"1258\" height=\"833\" srcset=\"https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/2019\/09\/iStock-1063894116.jpg 1258w, https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/2019\/09\/iStock-1063894116-300x199.jpg 300w, https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/2019\/09\/iStock-1063894116-840x556.jpg 840w, https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/2019\/09\/iStock-1063894116-200x132.jpg 200w, https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/2019\/09\/iStock-1063894116-768x509.jpg 768w\" sizes=\"auto, (max-width: 1258px) 100vw, 1258px\" \/><\/p>\n<h2><span class=\"ez-toc-section\" id=\"%C2%BFComo_se_diagnostica\"><\/span><span style=\"font-weight: 400;\">\u00bfC\u00f3mo se diagnostica?<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"font-weight: 400;\">El diagn\u00f3stico de la conjuntivitis v\u00edrica lo debe realizar el oftalm\u00f3logo. Por ello, si creemos que podemos tener una conjuntivitis (sea del tipo que sea), lo m\u00e1s recomendable ser\u00e1 acudir al m\u00e9dico para que pueda llevar a cabo una exploraci\u00f3n y hacer el diagn\u00f3stico correspondiente.\u00a0<\/span><\/p>\n<h2><span class=\"ez-toc-section\" id=\"%C2%BFCual_es_el_tratamiento_ideal_para_frenar_la_conjuntivitis_virica\"><\/span><span style=\"font-weight: 400;\">\u00bfCu\u00e1l es el tratamiento ideal para frenar la conjuntivitis v\u00edrica?<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"font-weight: 400;\">El tratamiento de la conjuntivitis v\u00edrica depender\u00e1 del tipo de virus y del diagn\u00f3stico que haya realizado el m\u00e9dico. En general, el tratamiento consistir\u00e1 en lo siguiente:\u00a0<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">La conjuntivitis v\u00edrica no suele ser agresiva. De hecho, en la mayor\u00eda de los casos sus s\u00edntomas desaparecen por s\u00ed solos.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Extremar la higiene ocular, tanto para evitar los contagios a otras personas como para evitar que la infecci\u00f3n se extienda.\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Lo m\u00e1s habitual es que el oftalm\u00f3logo recete <\/span><a href=\"https:\/\/www.clinicabaviera.com\/blog\/lagrimas-artificiales-que-son-y-para-que-sirven\/\"><span style=\"font-weight: 400;\">l\u00e1grimas artificiales<\/span><\/a><span style=\"font-weight: 400;\"> o de soluci\u00f3n salina. Sin embargo, es importante que el especialista defina qu\u00e9 tipo de l\u00e1grimas son las m\u00e1s adecuadas en cada caso.<\/span><\/li>\n<\/ul>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Los <a href=\"https:\/\/www.clinicabaviera.com\/blog\/para-que-se-usan-los-colirios-antibioticos\/\">colirios antibi\u00f3ticos<\/a> o de limpieza ocular (<\/span><a href=\"https:\/\/www.clinicabaviera.com\/blog\/mundo-baviera\/conoce-tus-ojos\/usos-del-suero-fisiologico-los-ojos\/\"><span style=\"font-weight: 400;\">suero fisiol\u00f3gico<\/span><\/a><span style=\"font-weight: 400;\">) son los que m\u00e1s se recetan en la primera fase de la enfermedad, m\u00e1s que nada para limpiar los ojos y los p\u00e1rpados y evitar la propagaci\u00f3n del virus que la causa u otras complicaciones. Los colirios antibi\u00f3ticos no tienen efecto contra los virus, pero ayudan a prevenir que, adem\u00e1s de la infecci\u00f3n v\u00edrica, el paciente pueda desarrollar tambi\u00e9n una infecci\u00f3n bacteriana.\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">En el caso de una conjuntivitis v\u00edrica causada por <\/span><a href=\"https:\/\/www.clinicabaviera.com\/blog\/bye-bye-gafas\/herpes-en-el-ojo-te-explicamos-lo-que-debes-saber\/\"><span style=\"font-weight: 400;\">herpes<\/span><\/a><span style=\"font-weight: 400;\">, ser\u00e1 necesario un tratamiento concreto y espec\u00edfico, ya que se trata de la m\u00e1s grave de las conjuntivitis v\u00edricas.\u00a0<\/span><\/li>\n<\/ul>\n<p><span class=\"embed-youtube\" style=\"text-align:center; display: block;\"><iframe loading=\"lazy\" class=\"youtube-player\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/xRoPE5nF3GY?version=3&#038;rel=1&#038;showsearch=0&#038;showinfo=1&#038;iv_load_policy=1&#038;fs=1&#038;hl=es-ES&#038;autohide=2&#038;wmode=transparent\" allowfullscreen=\"true\" style=\"border:0;\" sandbox=\"allow-scripts allow-same-origin allow-popups allow-presentation allow-popups-to-escape-sandbox\"><\/iframe><\/span><\/p>\n<h2><span class=\"ez-toc-section\" id=\"%C2%BFCuales_son_las_recomendaciones_para_evitar_el_contagio_de_la_conjuntivitis_virica\"><\/span><span style=\"font-weight: 400;\">\u00bfCu\u00e1les son las recomendaciones para evitar el contagio de la conjuntivitis v\u00edrica?<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Si por algo se caracteriza la conjuntivitis v\u00edrica es por la facilidad con la que se contagia. Basta con el solo hecho de tocar una superficie u objeto con restos de mucosa y luego pasar la mano por los ojos para que se transmita.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Algunos consejos que nos ayuda a evitar el contagio son los siguientes:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">No dejes tus gafas a otra persona. Los virus son especialistas en acoplarse a este tipo de superficies y luego trasladarse a tus ojos.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Si usas lentes de contacto, procura no pon\u00e9rtelas mientras tengas s\u00edntomas de conjuntivitis. Utiliza tus gafas.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">No compartas toallas, s\u00e1banas ni ropa con otras personas. Es decir, todas aquellas prendas que entren en contacto directo con tus ojos tienen que permanecer contigo durante el tiempo que dure la enfermedad. Una vez los s\u00edntomas se hayan ido, no olvides lavarlas bien.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">L\u00e1vate las manos con frecuencia con agua tibia y jab\u00f3n. Sobre todo, si vives con alguien y compartes un mismo espacio. <\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Adem\u00e1s de lavarse las manos con frecuencia, el paciente debe evitar tocarse o frotarse los ojos. Si lo hace, deber\u00e1 lavarse las manos despu\u00e9s de tocar los ojos.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">A la hora de retirar la secreci\u00f3n propia de esta enfermedad, hazlo con las manos bien lavadas y no reutilices ni el pa\u00f1uelo ni la toallita con la que lo hayas hecho. Usa una toallita para cada ojo, des\u00e9chalas tras la limpieza y l\u00e1vate las manos.<\/span><\/li>\n<li>No uses el mismo dispensador o frasco de gotas para los ojos para instilarte los medicamentos en el ojo infectado y en ojo no infectado.<\/li>\n<li>Los m\u00e1s peque\u00f1os de la casa, especialmente los ni\u00f1os que a\u00fan no andan y van gateando a todos los sitios, pasan mucho tiempo en el suelo y suelen llevarse las manos sucias a los ojos. Cuando padecen conjuntivitis debemos ser especialmente cuidadosos con la higiene para evitar complicaciones y que transmitan a otros ni\u00f1os o a los adultos los g\u00e9rmenes causantes de la conjuntivitis.<\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"%C2%BFQue_medidas_de_proteccion_pueden_aplicarse_en_verano\"><\/span><span style=\"font-weight: 400;\">\u00bfQu\u00e9 medidas de protecci\u00f3n pueden aplicarse en verano?<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"font-weight: 400;\">El verano es una estaci\u00f3n muy propicia para contraer conjuntivitis v\u00edricas, debido a que pasamos m\u00e1s tiempo en lugares concurridos, como la playa o la piscina.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Para evitar el contagio, debemos seguir las siguientes recomendaciones:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Usar gafas protectoras<\/b><span style=\"font-weight: 400;\">: tanto en la playa como en la piscina para nadar y bucear y, sobre todo, no compartirlas.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Ducharse<\/b><span style=\"font-weight: 400;\">: siempre que se salga del agua de la piscina o de la playa.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Extremar la higiene con las toallas<\/b><span style=\"font-weight: 400;\">: usar siempre toallas limpias y no compartirlas.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Utilizar gafas de sol<\/b><span style=\"font-weight: 400;\">: siempre que se est\u00e9 fuera del agua con el fin de proteger nuestros ojos de los rayos UV, la arena y otras part\u00edculas.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>No usar lentillas dentro del agua<\/b><span style=\"font-weight: 400;\">: si somos usuarios de lentes de contacto, no usarlas nunca dentro del agua en la playa o la piscina. El problema es que en estas circunstancias se incrementa la posibilidad de que se desarrollen bacterias en las lentillas, lo que adem\u00e1s de conjuntivitis, puede provocar infecciones m\u00e1s graves, como la <\/span><a href=\"https:\/\/www.clinicabaviera.com\/queratitis-o-ulcera-corneal\"><span style=\"font-weight: 400;\">queratitis<\/span><\/a><span style=\"font-weight: 400;\">. Esta patolog\u00eda es dif\u00edcil de tratar y causa dolor ocular y hasta disminuci\u00f3n de la agudeza visual.<\/span><\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"%C2%BFQue_complicaciones_puede_causar_la_conjuntivitis_virica\"><\/span><span style=\"font-weight: 400;\">\u00bfQu\u00e9 complicaciones puede causar la conjuntivitis v\u00edrica?<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Si una conjuntivitis v\u00edrica no se trata correctamente y a tiempo, el paciente puede presentar complicaciones graves como:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Inflamaci\u00f3n exagerada en el ojo.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Dificultades para llegar a abrir el p\u00e1rpado.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u00a0Dolor ocular intenso.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Malestar general.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Fiebre.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Dolor de cara y cabeza.\u00a0<\/span><\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"%C2%BFComo_saber_si_la_conjuntivitis_es_bacteriana_o_viral\"><\/span><span style=\"font-weight: 400;\">\u00bfC\u00f3mo saber si la conjuntivitis es bacteriana o viral?<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"font-weight: 400;\">En el caso de la conjuntivitis v\u00edrica, es muy poco habitual la presencia de mucosidad en el ojo. Si la hay, suele ser escasa y con aspecto blanquecino. Esto es importante porque, si aparece abundante mucosidad (que luego suele convertirse en costra y lega\u00f1as en el p\u00e1rpado), suele ser indicativo de que no estamos ante una conjuntivitis v\u00edrica sino <\/span><a href=\"https:\/\/www.clinicabaviera.com\/blog\/conjuntivitis-bacteriana-causas-sintomas-y-tratamiento\/\"><span style=\"font-weight: 400;\">bacteriana<\/span><\/a><span style=\"font-weight: 400;\">.<\/span><\/p>\n<h2><span class=\"ez-toc-section\" id=\"%C2%BFCuando_ir_al_medico_por_una_conjuntivitis\"><\/span><span style=\"font-weight: 400;\">\u00bfCu\u00e1ndo ir al m\u00e9dico por una conjuntivitis?<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Siempre que se crea que se puede tener una conjuntivitis se debe ir al m\u00e9dico. De esta forma, adem\u00e1s del diagn\u00f3stico concreto del tipo de conjuntivitis, tambi\u00e9n se prescribir\u00e1 el tratamiento espec\u00edfico para cada caso. Esto permite una mejor y m\u00e1s r\u00e1pida recuperaci\u00f3n, adem\u00e1s de evitar otros problemas y complicaciones asociadas a la conjuntivitis.\u00a0<\/span><\/p>\n<h2><span class=\"ez-toc-section\" id=\"%C2%BFExiste_una_vacuna_para_prevenir_la_conjuntivitis\"><\/span>\u00bfExiste una vacuna para prevenir la conjuntivitis?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>No existe una vacuna que prevenga todos los tipos de conjuntivitis. Sin embargo, hay vacunas que protegen contra algunas enfermedades bacterianas y virales que se asocian a algunas clases de conjuntivitis:<\/p>\n<ul>\n<li>Rubeola.<\/li>\n<li>Sarampi\u00f3n.<\/li>\n<li>Varicela<\/li>\n<li>Herpes zoster.<\/li>\n<li>Enfermedad neumoc\u00f3cida\u2026<\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"Fuentes\"><\/span><span style=\"font-weight: 400;\">Fuentes<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<ul>\n<li><a href=\"https:\/\/www.aao.org\/salud-ocular\/enfermedades\/conjuntivitis-ojo-rojo\" rel=\"nofollow\">Academia Americana de Oftalmolog\u00eda (AAO) &#8211; Conjuntivitis: \u00bfQu\u00e9 es el ojo rojo?<\/a><\/li>\n<li><a href=\"https:\/\/www.aao.org\/salud-ocular\/enfermedades\/queratitis-herpetica\" rel=\"nofollow\">Academia Americana de Oftalmolog\u00eda (AAO) &#8211; \u00bfQu\u00e9 es la queratitis herp\u00e9tica?<\/a><\/li>\n<\/ul>\n<hr \/>\n<pre class=\"ti-widget\" style=\"display: none\"><template id=\"trustindex-google-widget-html\"><div class=\" ti-widget  ti-goog ti-review-text-mode-readmore ti-text-align-left\" data-no-translation=\"true\" data-plugin-version=\"13.3.2\" data-layout-id=\"5\" data-layout-category=\"slider\" data-set-id=\"light-minimal\" data-pid=\"\" data-language=\"es\" data-close-locale=\"Cerca\" data-review-target-width=\"275\" data-css-version=\"2\" data-reply-by-locale=\"Respuesta del propietario\" data-only-rating-locale=\"Este usuario solo dej\u00f3 una calificaci\u00f3n.\" data-pager-autoplay-timeout=\"6\"> <div class=\"ti-widget-container ti-col-4\"> <div class=\"ti-footer ti-footer-grid source-Google\"> <div class=\"ti-fade-container\"> <div class=\"ti-rating-text\"> <strong class=\"ti-rating ti-rating-large\"> EXCELENTE <\/strong> <\/div> <span class=\"ti-stars star-lg\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><\/span> <div class=\"ti-rating-text\"> <span class=\"nowrap\">A base de <strong>570 rese\u00f1as<\/strong><\/span> <\/div> <div class=\"ti-large-logo\"> <div class=\"ti-v-center\"> <trustindex-image class=\"ti-logo-fb\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/logo.svg\" width=\"150\" height=\"25\" loading=\"lazy\" alt=\"Google\"><\/trustindex-image> <\/div> <\/div> <\/div> <\/div> <div class=\"ti-reviews-container\"> <div class=\"ti-controls\"> <div class=\"ti-next\" aria-label=\"Siguiente rese\u00f1a\" role=\"button\" tabindex=\"0\"><\/div> <div class=\"ti-prev\" aria-label=\"Rese\u00f1a anterior\" role=\"button\" tabindex=\"0\"><\/div> <\/div> <div class=\"ti-reviews-container-wrapper\">  <div data-empty=\"0\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-time=\"\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publicado en Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocKWHKmwDoN8jelN8JHWQw2buiU4ji6WyuVq8pcV4kRI=w40-h40-c-rp-mo-br100\" alt=\"Karelys Asencio Torres profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Karelys Asencio Torres <\/div> <div class=\"ti-date\">05\/03\/2024<\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex verifica que la fuente original de la rese\u00f1a sea Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Esta cl\u00ednica sin duda es la mejor !! El trato en recepci\u00f3n y de los m\u00e9dicos es excepcional. Estoy muy contenta con los resultados. Muchas gracias !<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Ocultar\" data-open-text=\"Leer m\u00e1s\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-time=\"\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publicado en Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocJx5lc8VzH_Kx5vNl4iC9Qof6IGYcXj03vtn_CJ67tj=w40-h40-c-rp-mo-br100\" alt=\"Vanesa Delgado Arcos profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Vanesa Delgado Arcos <\/div> <div class=\"ti-date\">01\/03\/2024<\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex verifica que la fuente original de la rese\u00f1a sea Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Much\u00edsima profesionalidad por parte de todo el equipo desde recepci\u00f3n y por supuesto si doctor.Estoy totalmente complacida por el resultado de la operaci\u00f3n y posteriores seguimientos.100%recomendable.<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Ocultar\" data-open-text=\"Leer m\u00e1s\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-time=\"\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publicado en Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjViSSX9rp-UKWvltgBF-J8MwK4Ga5nbJvaYsl3jYkAh2LQ=w40-h40-c-rp-mo-br100\" alt=\"Jorge Carnicero profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Jorge Carnicero <\/div> <div class=\"ti-date\">27\/02\/2024<\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex verifica que la fuente original de la rese\u00f1a sea Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Me oper\u00e9 ya hace un mes con laser de miop\u00eda y no pude tomar mejor decisi\u00f3n, buen asesoramiento desde el principio, un equipo maravilloso que est\u00e1n disponibles para cualquier consulta y unos resultados \u00f3ptimos, sensaci\u00f3n inmejorable poder ver otra vez perfectamente sin necesidad de gafas.<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Ocultar\" data-open-text=\"Leer m\u00e1s\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-time=\"\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publicado en Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocLf5YTDoqTOI9RiEgIqmgY0sL1jjWzGDFlZUKGefO3E=w40-h40-c-rp-mo-br100\" alt=\"Carlos \u00c1ngel P\u00e9rez profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Carlos \u00c1ngel P\u00e9rez <\/div> <div class=\"ti-date\">27\/02\/2024<\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex verifica que la fuente original de la rese\u00f1a sea Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Atenci\u00f3n muy buena de la doctora y de las auxiliares<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Ocultar\" data-open-text=\"Leer m\u00e1s\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-time=\"\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publicado en Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocLJ9j-vNwboPm0yglVXrs4FTPEon3Om3ZTJi7xaqcjl=w40-h40-c-rp-mo-br100\" alt=\"Virginia Jimenez profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Virginia Jimenez <\/div> <div class=\"ti-date\">22\/02\/2024<\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex verifica que la fuente original de la rese\u00f1a sea Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->He recibido un trato espectacular por parte de todos los trabajadores de la cl\u00ednica de M\u00f3stoles.\nLa operaci\u00f3n me la realiz\u00f3 el doctor Rafael, y sali\u00f3 todo muy muy bien me operado de miop\u00eda y astigmatismo, y el mismo d\u00eda por la noche ya pod\u00eda ver y hacer vida normal. Lo recomiendo 100 por 100.\nLlegue con miedo por que la vista es algo muy delicado y a d\u00eda de hoy la mejor decisi\u00f3n que tom\u00e9 fue quitarme las gafas y hacerlo con ellos.\n\nGracias<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Ocultar\" data-open-text=\"Leer m\u00e1s\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-time=\"\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publicado en Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjVdbd3Sm-F_C3qjnSPIEeZ28H3K404OeYdISk2TIzCrhH0=w40-h40-c-rp-mo-ba2-br100\" alt=\"Isidro Hoyas profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Isidro Hoyas <\/div> <div class=\"ti-date\">20\/02\/2024<\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex verifica que la fuente original de la rese\u00f1a sea Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Buenos profesionales y las chicas muy amables y atentas<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Ocultar\" data-open-text=\"Leer m\u00e1s\"><\/span> <\/div> <\/div>  <\/div> <div class=\"ti-controls-line\"> <div class=\"dot\"><\/div> <\/div>   <\/div> <\/div> <\/div> <\/template><\/pre><div data-src=\"https:\/\/cdn.trustindex.io\/loader.js?wp-widget\" data-template-id=\"trustindex-google-widget-html\" data-css-url=\"https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/trustindex-google-widget.css?1787550621\"><\/div>\n<hr \/>\n<p>&nbsp;<\/p>\n<p><!-- This site is converting visitors into subscribers and customers with OptinMonster - http:\/\/optinmonster.com :: Campaign Title: CTA Form Ojo con tus ojos --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La conjuntivitis v\u00edrica es una de las afecciones oculares m\u00e1s comunes. Esta enfermedad aparece cuando uno o varios virus infectan la conjuntiva del ojo, la membrana m\u00e1s externa que recubre la superficie del ojo y el interior del p\u00e1rpado.\u00a0 Por suerte, con las precauciones y el tratamiento correspondiente, se trata de una infecci\u00f3n que puede [&hellip;]<\/p>\n","protected":false},"author":38,"featured_media":31412,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":true},"categories":[1143,1144],"tags":[1560,1561],"ppma_author":[2264],"class_list":["post-7712","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bye-bye-gafas","category-conoce-tus-ojos","tag-conjuntivitis-virica-tratamiento","tag-conjuntivitis-vision-borrosa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Conjuntivitis v\u00edrica: tratamiento y recomendaciones - Blog de Baviera antes Cl\u00ednica Baviera<\/title>\n<meta name=\"description\" content=\"La conjuntivitis v\u00edrica es una de las afecciones oculares m\u00e1s comunes y aparece cuando diferentes virus infectan la conjuntiva del ojo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.clinicabaviera.com\/blog\/conjuntivitis-virica-tratamiento-recomendaciones\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conjuntivitis v\u00edrica: tratamiento y recomendaciones - Blog de Baviera antes Cl\u00ednica Baviera\" \/>\n<meta property=\"og:description\" content=\"La conjuntivitis v\u00edrica es una de las afecciones oculares m\u00e1s comunes y aparece cuando diferentes virus infectan la conjuntiva del ojo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.clinicabaviera.com\/blog\/conjuntivitis-virica-tratamiento-recomendaciones\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog de Baviera antes Cl\u00ednica Baviera\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CLINICABAVIERA\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-01T06:00:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-13T12:27:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/2019\/09\/iStock-1063894116.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1258\" \/>\n\t<meta property=\"og:image:height\" content=\"833\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dra. \u00c1ngeles Gim\u00e9nez-Almenara\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dra. \u00c1ngeles Gim\u00e9nez-Almenara\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conjuntivitis v\u00edrica: tratamiento y recomendaciones - Blog de Baviera antes Cl\u00ednica Baviera","description":"La conjuntivitis v\u00edrica es una de las afecciones oculares m\u00e1s comunes y aparece cuando diferentes virus infectan la conjuntiva del ojo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.clinicabaviera.com\/blog\/conjuntivitis-virica-tratamiento-recomendaciones\/","og_locale":"es_ES","og_type":"article","og_title":"Conjuntivitis v\u00edrica: tratamiento y recomendaciones - Blog de Baviera antes Cl\u00ednica Baviera","og_description":"La conjuntivitis v\u00edrica es una de las afecciones oculares m\u00e1s comunes y aparece cuando diferentes virus infectan la conjuntiva del ojo.","og_url":"https:\/\/www.clinicabaviera.com\/blog\/conjuntivitis-virica-tratamiento-recomendaciones\/","og_site_name":"Blog de Baviera antes Cl\u00ednica Baviera","article_publisher":"https:\/\/www.facebook.com\/CLINICABAVIERA","article_published_time":"2023-03-01T06:00:56+00:00","article_modified_time":"2025-02-13T12:27:07+00:00","og_image":[{"width":1258,"height":833,"url":"https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/2019\/09\/iStock-1063894116.jpg","type":"image\/jpeg"}],"author":"Dra. \u00c1ngeles Gim\u00e9nez-Almenara","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Dra. \u00c1ngeles Gim\u00e9nez-Almenara","Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.clinicabaviera.com\/blog\/conjuntivitis-virica-tratamiento-recomendaciones\/#article","isPartOf":{"@id":"https:\/\/www.clinicabaviera.com\/blog\/conjuntivitis-virica-tratamiento-recomendaciones\/"},"author":{"name":"Dra. Angeles Gimenez-Almenara","@id":"https:\/\/www.clinicabaviera.com\/blog\/#\/schema\/person\/9ff3974696825f955bf2656db28a5c20"},"headline":"Conjuntivitis v\u00edrica: tratamiento y recomendaciones","datePublished":"2023-03-01T06:00:56+00:00","dateModified":"2025-02-13T12:27:07+00:00","mainEntityOfPage":{"@id":"https:\/\/www.clinicabaviera.com\/blog\/conjuntivitis-virica-tratamiento-recomendaciones\/"},"wordCount":1605,"commentCount":4,"publisher":{"@id":"https:\/\/www.clinicabaviera.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.clinicabaviera.com\/blog\/conjuntivitis-virica-tratamiento-recomendaciones\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/2019\/09\/iStock-1063894116.jpg","keywords":["conjuntivitis virica tratamiento","conjuntivitis vision borrosa"],"articleSection":["Bye bye gafas","Cuida tus ojos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.clinicabaviera.com\/blog\/conjuntivitis-virica-tratamiento-recomendaciones\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.clinicabaviera.com\/blog\/conjuntivitis-virica-tratamiento-recomendaciones\/","url":"https:\/\/www.clinicabaviera.com\/blog\/conjuntivitis-virica-tratamiento-recomendaciones\/","name":"Conjuntivitis v\u00edrica: tratamiento y recomendaciones - Blog de Baviera antes Cl\u00ednica Baviera","isPartOf":{"@id":"https:\/\/www.clinicabaviera.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.clinicabaviera.com\/blog\/conjuntivitis-virica-tratamiento-recomendaciones\/#primaryimage"},"image":{"@id":"https:\/\/www.clinicabaviera.com\/blog\/conjuntivitis-virica-tratamiento-recomendaciones\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/2019\/09\/iStock-1063894116.jpg","datePublished":"2023-03-01T06:00:56+00:00","dateModified":"2025-02-13T12:27:07+00:00","description":"La conjuntivitis v\u00edrica es una de las afecciones oculares m\u00e1s comunes y aparece cuando diferentes virus infectan la conjuntiva del ojo.","breadcrumb":{"@id":"https:\/\/www.clinicabaviera.com\/blog\/conjuntivitis-virica-tratamiento-recomendaciones\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.clinicabaviera.com\/blog\/conjuntivitis-virica-tratamiento-recomendaciones\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.clinicabaviera.com\/blog\/conjuntivitis-virica-tratamiento-recomendaciones\/#primaryimage","url":"https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/2019\/09\/iStock-1063894116.jpg","contentUrl":"https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/2019\/09\/iStock-1063894116.jpg","width":1258,"height":833,"caption":"conjuntivitis v\u00edrica"},{"@type":"BreadcrumbList","@id":"https:\/\/www.clinicabaviera.com\/blog\/conjuntivitis-virica-tratamiento-recomendaciones\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.clinicabaviera.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Conjuntivitis v\u00edrica: tratamiento y recomendaciones"}]},{"@type":"WebSite","@id":"https:\/\/www.clinicabaviera.com\/blog\/#website","url":"https:\/\/www.clinicabaviera.com\/blog\/","name":"Blog de Baviera antes Cl\u00ednica Baviera","description":"Informaci\u00f3n sobre la salud visual","publisher":{"@id":"https:\/\/www.clinicabaviera.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.clinicabaviera.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.clinicabaviera.com\/blog\/#organization","name":"Baviera","url":"https:\/\/www.clinicabaviera.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.clinicabaviera.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/2021\/02\/logo.png","contentUrl":"https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/2021\/02\/logo.png","width":526,"height":164,"caption":"Baviera"},"image":{"@id":"https:\/\/www.clinicabaviera.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CLINICABAVIERA"]},{"@type":"Person","@id":"https:\/\/www.clinicabaviera.com\/blog\/#\/schema\/person\/9ff3974696825f955bf2656db28a5c20","name":"Dra. Angeles Gimenez-Almenara","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.clinicabaviera.com\/blog\/wp-content\/uploads\/2022\/12\/Dra.-Angeles-Gimenez-Almenara-min.jpg8eb112c5a4989397526ebf6a4e68be4e","url":"https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/2022\/12\/Dra.-Angeles-Gimenez-Almenara-min.jpg","contentUrl":"https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/2022\/12\/Dra.-Angeles-Gimenez-Almenara-min.jpg","caption":"Dra. Angeles Gimenez-Almenara"},"description":"La Dra. \u00c1ngeles Gim\u00e9nez-Almenara es oftalm\u00f3logo especialista en cirug\u00eda refractiva, cirug\u00eda de la presbicia, cirug\u00eda de cataratas, estrabismo y oftalmolog\u00eda pedi\u00e1trica y oculoplastia. Desarrolla su labor asistencial en Baviera C\u00f3rdoba.","sameAs":["https:\/\/www.clinicabaviera.com\/clinica-oftalmologica-medico\/angeles-gimenez-almenara"],"url":"https:\/\/www.clinicabaviera.com\/clinica-oftalmologica-medico\/angeles-gimenez-almenara"}]}},"jetpack_shortlink":"https:\/\/wp.me\/p3aNmD-20o","jetpack_sharing_enabled":true,"authors":[{"term_id":2264,"user_id":38,"is_guest":0,"slug":"dra-angeles-gimenez-almenara","display_name":"Dra. \u00c1ngeles Gim\u00e9nez-Almenara","avatar_url":{"url":"https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/2022\/12\/Dra.-Angeles-Gimenez-Almenara-min.jpg","url2x":"https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/2022\/12\/Dra.-Angeles-Gimenez-Almenara-min.jpg"},"author_category":"","user_url":"https:\/\/www.clinicabaviera.com\/clinica-oftalmologica-medico\/angeles-gimenez-almenara","last_name":"Gim\u00e9nez-Almenara","first_name":"\u00c1ngeles","job_title":"","description":"La Dra. \u00c1ngeles Gim\u00e9nez-Almenara es oftalm\u00f3logo especialista en cirug\u00eda refractiva, cirug\u00eda de la presbicia, cirug\u00eda de cataratas, estrabismo y oftalmolog\u00eda pedi\u00e1trica y oculoplastia. Desarrolla su labor asistencial en Cl\u00ednica Baviera C\u00f3rdoba."}],"jetpack_featured_media_url":"https:\/\/cdn.clinicabaviera.com\/blog\/wp-content\/uploads\/2019\/09\/iStock-1063894116.jpg","_links":{"self":[{"href":"https:\/\/www.clinicabaviera.com\/blog\/wp-json\/wp\/v2\/posts\/7712","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.clinicabaviera.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.clinicabaviera.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.clinicabaviera.com\/blog\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/www.clinicabaviera.com\/blog\/wp-json\/wp\/v2\/comments?post=7712"}],"version-history":[{"count":26,"href":"https:\/\/www.clinicabaviera.com\/blog\/wp-json\/wp\/v2\/posts\/7712\/revisions"}],"predecessor-version":[{"id":36000,"href":"https:\/\/www.clinicabaviera.com\/blog\/wp-json\/wp\/v2\/posts\/7712\/revisions\/36000"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.clinicabaviera.com\/blog\/wp-json\/wp\/v2\/media\/31412"}],"wp:attachment":[{"href":"https:\/\/www.clinicabaviera.com\/blog\/wp-json\/wp\/v2\/media?parent=7712"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.clinicabaviera.com\/blog\/wp-json\/wp\/v2\/categories?post=7712"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.clinicabaviera.com\/blog\/wp-json\/wp\/v2\/tags?post=7712"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.clinicabaviera.com\/blog\/wp-json\/wp\/v2\/ppma_author?post=7712"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}